{"id":9729,"date":"2015-06-18T09:56:05","date_gmt":"2015-06-18T07:56:05","guid":{"rendered":"http:\/\/ddurv.taller.fesomia.net\/?p=9729"},"modified":"2015-06-18T11:14:42","modified_gmt":"2015-06-18T09:14:42","slug":"el-ctns-estudia-los-efectos-beneficiosos-para-la-salud-del-consumo-de-zumo-de-naranja-natural","status":"publish","type":"post","link":"https:\/\/ddurv.taller.fesomia.net\/es\/el-ctns-estudia-los-efectos-beneficiosos-para-la-salud-del-consumo-de-zumo-de-naranja-natural\/","title":{"rendered":"El CTNS estudia los efectos beneficiosos para la salud del consumo de zumo de naranja natural"},"content":{"rendered":"<p>Comprobar los efectos saludables del consumo de zumo de naranja 100% natural en personas ligeramente hipertensas. Este es el objetivo que persigue el estudio del Centro Tecnol\u00f3gico de Nutrici\u00f3n y Salud (CTNS). Para llevarlo a cabo, se utilizar\u00e1n varios marcadores bioqu\u00edmicos para evaluar su efecto, a grandes rasgos se quiere comprobar si la presencia de un compuesto del zumo de naranja (la hesperidina) tiene efectos beneficiosos sobre la presi\u00f3n sangu\u00ednea. Para ello, se llevar\u00e1 a cabo un estudio con 252 voluntarios ligeramente hipertensos, que deber\u00e1n consumir el zumo de naranja durante 12 semanas.<\/p>\n<p>Antes de empezar, durante y al final del estudio, se evaluar\u00e1n varios par\u00e1metros antropom\u00e9tricos, bioqu\u00edmicos y de salud, incluyendo una novedosa aproximaci\u00f3n nutrigen\u00f3mica \u2013 utilizando t\u00e9cnicas \u00d3micas para obtener una visi\u00f3n m\u00e1s hol\u00edstica de lo que pasa a nivel bioqu\u00edmico en nuestro organismo \u2013 que el equipo de Florida, que financia el proyecto, ha valorado muy positivamente. El Dr. Llu\u00eds Arola, director del CTNS e investigador principal del estudio, firm\u00f3 el contrato el pasado mes de abril, despu\u00e9s de la aprobaci\u00f3n por parte del organismo concedente de Estados Unidos.<\/p>\n<p>El estudio se desarrollar\u00e1 en el edificio del CTNS en los espacios habilitados para \u00e9l, y se iniciar\u00e1 en septiembre de 2015 hasta septiembre de 2017. El CTNS (que forma parte de la red TECNIO) est\u00e1 actualmente ultimando los preparativos del estudio con el equipo de la Dra. Rosa Sol\u00e0, catedr\u00e1tica de Medicina de la Universidad Rovira i Virgili, y cuenta ya con la aprobaci\u00f3n del Comit\u00e9 \u00c9tico de Investigaci\u00f3n del Hospital Universitario Sant Joan de Reus.<\/p>\n<p>El estudio contar\u00e1 con la implicaci\u00f3n de un grupo de profesionales acad\u00e9micos, cient\u00edficos y de la salud, la participaci\u00f3n de 252 voluntarios, la realizaci\u00f3n de m\u00e1s de 1.700 visitas de seguimiento, el an\u00e1lisis de m\u00e1s de 26.000 muestras de plasma y el consumo de m\u00e1s de 7.000 litros de zumo de naranja 100% natural procedente de Florida.<\/p>\n<p>El Florida Department of Citrus de Estados Unidos convoc\u00f3 en 2014 una licitaci\u00f3n internacional para estudiar los efectos beneficiosos del zumo de naranja. Esta licitaci\u00f3n est\u00e1 financiada por un consorcio internacional llamado la Citrus Health Claim Initiative, formado por el Estado de Florida, la Asociaci\u00f3n Internacional de fabricantes de zumo v\u00eda su filial europea (AIJN) y los mayores productores de c\u00edtricos y zumos de Brasil, como parte de su estrategia cient\u00edfica internacional.<\/p>\n<p>El CTNS present\u00f3 la propuesta que resultar\u00eda ganadora, proponiendo un estudio de intervenci\u00f3n nutricional paralelo, doble ciego, controlado con placebo, para evaluar los efectos de un consumo cr\u00f3nico y agudo de un zumo 100% naranja de Florida, por importe de 536.000 d\u00f3lares.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una licitaci\u00f3n p\u00fablica con competidores de todo el mundo, el CTNS ha conseguido un contrato de m\u00e1s de 500.000 d\u00f3lares para realizar un estudio de intervenci\u00f3n nutricional con 250 voluntarios para evaluar los beneficios del consumo de un zumo de naranja de 100% natural, en colaboraci\u00f3n con investigadores de la URV<\/p>\n","protected":false},"author":12,"featured_media":9719,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[102,254,83,100,124,120],"tags":[1700,1701,1702],"class_list":["post-9729","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comciencia-es","category-facultat-medicina-ciencias-salud","category-general-es","category-investigacion","category-portada-es","category-salud","tag-ctns-es","tag-lluis-arola-es","tag-rosa-sola-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/9729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/comments?post=9729"}],"version-history":[{"count":0,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/9729\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media\/9719"}],"wp:attachment":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media?parent=9729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/categories?post=9729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/tags?post=9729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}