{"id":9660,"date":"2014-07-22T12:57:37","date_gmt":"2014-07-22T10:57:37","guid":{"rendered":"http:\/\/ddurv.taller.fesomia.net\/?p=9660"},"modified":"2015-06-16T13:05:10","modified_gmt":"2015-06-16T11:05:10","slug":"el-iciq-pone-en-funcionamiento-un-laboratorio-de-experimentacion-de-alto-rendimiento-unico-en-europa","status":"publish","type":"post","link":"https:\/\/ddurv.taller.fesomia.net\/es\/el-iciq-pone-en-funcionamiento-un-laboratorio-de-experimentacion-de-alto-rendimiento-unico-en-europa\/","title":{"rendered":"El ICIQ pone en funcionamiento un laboratorio de experimentaci\u00f3n de alto rendimiento \u00fanico en Europa"},"content":{"rendered":"<p>Coincidiendo con los actos de celebraci\u00f3n del d\u00e9cimo aniversario del Instituto Catal\u00e1n de Investigaci\u00f3n Qu\u00edmica\u00a0(ICIQ) se ha inaugurado el Laboratorio\u00a0CELLEX-ICIQ de Experimentaci\u00f3n de Alto Rendimiento, instalaci\u00f3n de investigaci\u00f3n \u00fanica en Europa puesto que s\u00f3lo hay dos laboratorios de estas caracter\u00edsticas en los Estados Unidos. Esta instalaci\u00f3n permitir\u00e1 al\u00a0ICIQ acelerar el descubrimiento de nuevas mol\u00e9culas para crear nuevos f\u00e1rmacos y catalizadores a trav\u00e9s de procesos m\u00e1s limpios, eficaces y baratos.<\/p>\n<p>Este tipo de laboratorio ofrece la posibilidad de ejecutar y analizar un gran n\u00famero de reacciones en muy poco tiempo, y por lo tanto, acelerar de forma muy notable la optimizaci\u00f3n de los procesos estudiados o bien el descubrimiento de nuevos procesos. Por otro lado, la capacidad de hacer muchas reacciones en muy poco tiempo, tambi\u00e9n lleva\u00a0a seguir v\u00edas de descubrimiento a menudo poco exploradas como son los estudios irracionales de optimizaci\u00f3n o bien el estudio de procesos dif\u00edciles y a priori con pocas posibilidades de \u00e9xito.<\/p>\n<p>La Fundaci\u00f3n\u00a0Cellex ha donado 2,5 millones de euros al\u00a0ICIQ para poder hacer este laboratorio. La donaci\u00f3n permitir\u00e1 la incorporaci\u00f3n de dos nuevos grupos de investigaci\u00f3n dentro del programa\u00a0Starting\u00a0Career del\u00a0ICIQ y la creaci\u00f3n de un programa de\u00a0postdoctorado para investigadores que hagan un uso intensivo de esta\u00a0instalaci\u00f3n. Adem\u00e1s, con esta dotaci\u00f3n se cubrir\u00e1n los gastos de funcionamiento y personal t\u00e9cnico del laboratorio.<\/p>\n<p>El conseller\u00a0de Econom\u00eda y Conocimiento, Andreu Mas-Colell, ha inaugurado el Laboratorio\u00a0CELLEX-ICIQ de Experimentaci\u00f3n de Alto Rendimiento (CELLEX-ICIQ\u00a0HTE\u00a0Laboratory) que ha sido precedida por un acto institucional donde se ha hecho balance de estos primeros 10 a\u00f1os del\u00a0Instituto Catal\u00e1n de Investigaci\u00f3n Qu\u00edmica (ICIQ). Han intervenido, tambi\u00e9n, el director del\u00a0ICIQ, Miquel \u00c0ngel\u00a0 Peric\u00e0s; el alcalde de Tarragona, Josep F\u00e8lix Ballesteros; el director de Bayer y miembro del Patronato del\u00a0ICIQ, Jes\u00fas\u00a0Loma-Ossorio; el rector de la URV, Josep Anton\u00a0Ferr\u00e9, y la secretaria de Estado de I+D+I, Carmen Vela.<\/p>\n<figure id=\"attachment_9655\" aria-labelledby=\"figcaption_attachment_9655\" class=\"wp-caption alignnone\" style=\"width: 766px\"><a href=\"http:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/Foto-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9655\" src=\"http:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/Foto-1.jpg\" alt=\"El conseller, Andreu Mas-Colell, se dirige a los asistentes en la presentaci\u00f3n del Laboratorio CELLEX-ICIQ de Experimentaci\u00f3n de Alto Rendimiento (CELLEX-ICIQ HTE Laboratory).\" width=\"766\" height=\"575\" srcset=\"https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/Foto-1.jpg 766w, https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/Foto-1-300x225.jpg 300w, https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/Foto-1-384x287.jpg 384w, https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/Foto-1-800x600.jpg 800w\" sizes=\"auto, (max-width: 766px) 100vw, 766px\" \/><\/a><figcaption id=\"figcaption_attachment_9655\" class=\"wp-caption-text\">El conseller, Andreu Mas-Colell, se dirige a los asistentes en la presentaci\u00f3n del Laboratorio CELLEX-ICIQ de Experimentaci\u00f3n de Alto Rendimiento (CELLEX-ICIQ HTE Laboratory).<\/figcaption><\/figure>\n<p>El director del\u00a0ICIQ, Miquel\u00a0Peric\u00e0s ha destacado \u00abla tarea de los trabajadores del\u00a0ICIQ, que han estado\u00a0comprometidos con los objetivos del centro como la excelencia en ciencia, el alto nivel en educaci\u00f3n y el servicio a la sociedad\u00bb. Por su parte, el conseller\u00a0ha valorado \u00abla existencia del cl\u00faster qu\u00edmico de Tarragona, que fue el origen de este instituto\u00bb.<\/p>\n<h5>Acreditado como centro de Excelencia\u00a0Severo Ochoa<\/h5>\n<p>El\u00a0ICIQ, uno de los miembros del Campus de Excelencia Internacional Catalu\u00f1a Sur (CEICS) inici\u00f3 su\u00a0actividad de investigaci\u00f3n en 2004 y al cabo\u00a0de 10 a\u00f1os ha acontecido uno de los centros en investigaci\u00f3n qu\u00edmica de referencia a nivel internacional. Actualmente cuenta con 19 grupos de investigaci\u00f3n trabajando en el \u00e1mbito de la cat\u00e1lisis (mejora y descubrimiento de nuevos procesos qu\u00edmicos m\u00e1s sostenibles y \u00fatiles para el desarrollo de nuevos f\u00e1rmacos y nuevas fuentes de energ\u00eda) y de las energ\u00edas renovables (generaci\u00f3n de hidr\u00f3geno a partir del agua, fotovoltaica molecular, conversi\u00f3n de CO2 en materiales y combustibles de inter\u00e9s industrial). El ICIQ ha sido acreditado como centro de Excelencia Severo Ochoa, ha obtenido 7 ayudas de la European Research Council (ERC Grants) y 8 de sus investigadores son Profesores ICREA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fundaci\u00f3n Cellex aporta 2,5 millones de euros en la puesta en marcha de este laboratorio que ha sido inaugurado por el conseller Mas-Colell en el marco de la celebraci\u00f3n del 10\u00ba aniversario del Instituto Catal\u00e1n de Investigaci\u00f3n Qu\u00edmica (ICIQ)<\/p>\n","protected":false},"author":11,"featured_media":9658,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[117,102,124],"tags":[1685,1687,569,1307,566],"class_list":["post-9660","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-y-tecnologia","category-comciencia-es","category-portada-es","tag-cellex-iciq-hte-laboratory","tag-fundacion-cellex","tag-iciq","tag-icrea","tag-quimica"],"acf":[],"_links":{"self":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/9660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/comments?post=9660"}],"version-history":[{"count":0,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/9660\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media\/9658"}],"wp:attachment":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media?parent=9660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/categories?post=9660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/tags?post=9660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}