{"id":9649,"date":"2014-07-23T11:12:08","date_gmt":"2014-07-23T09:12:08","guid":{"rendered":"http:\/\/ddurv.taller.fesomia.net\/?p=9649"},"modified":"2015-06-16T11:37:34","modified_gmt":"2015-06-16T09:37:34","slug":"93-profesores-de-secundaria-participan-en-los-cursos-de-formacion-academica-del-programa-aprofundiments","status":"publish","type":"post","link":"https:\/\/ddurv.taller.fesomia.net\/es\/93-profesores-de-secundaria-participan-en-los-cursos-de-formacion-academica-del-programa-aprofundiments\/","title":{"rendered":"93 profesores de secundaria participan en los cursos de formaci\u00f3n acad\u00e9mica del programa &#8216;Aprofundiments&#8217;"},"content":{"rendered":"<p>Este a\u00f1o se ha celebrado la segunda edici\u00f3n de estos cursos de actualizaci\u00f3n universitaria al profesorado de secundaria, que ha pasado de dos cursos, de ciencia e historia -que se impartieron en la edici\u00f3n de 2013-, hasta siete cursos de diferentes disciplinas acad\u00e9micas que se han impartido en esta ocasi\u00f3n.<\/p>\n<p>Estos son\u00a0los cursos que se han impartido en esta edici\u00f3n del programa <em>Aprofundiments<\/em>:<\/p>\n<ul>\n<li class=\"first\">Historia del mundo contempor\u00e1neo. Nuevas aportaciones y propuestas de trabajo al aula (II)<\/li>\n<li>La literatura [catalana] en el aula de secundaria y bachillerato: modelos de trabajo<\/li>\n<li>La normativa gramatical [de la lengua catalana] hoy: estado de la cuesti\u00f3n y herramientas de consulta<\/li>\n<li>Biotecnolog\u00eda <em>low cost<\/em><\/li>\n<li>Rob\u00f3tica educativa<\/li>\n<li>140 caracteres punto com<\/li>\n<li class=\"last\">Talleres de programaci\u00f3n con Scratch para secundaria<\/li>\n<\/ul>\n<figure id=\"attachment_9647\" aria-labelledby=\"figcaption_attachment_9647\" class=\"wp-caption alignnone\" style=\"width: 700px\"><a href=\"http:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/DSCF6642_ok.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9647\" src=\"http:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/DSCF6642_ok.jpg\" alt=\"Los asistentes participan en las clases de los cursos de formaci\u00f3n en la URV.\" width=\"700\" height=\"525\" srcset=\"https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/DSCF6642_ok.jpg 700w, https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/DSCF6642_ok-300x225.jpg 300w, https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/DSCF6642_ok-384x287.jpg 384w, https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/DSCF6642_ok-800x600.jpg 800w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><figcaption id=\"figcaption_attachment_9647\" class=\"wp-caption-text\">Los asistentes participan en las clases de los cursos de formaci\u00f3n en la URV.<\/figcaption><\/figure>\n<p><em>Aprofundiments <\/em>es una actividad organizada por el Centro de Atenci\u00f3n al Estudiante (CAE) y el <em>Institut de Ci\u00e8ncies de l\u2019Educaci\u00f3<\/em>\u00a0de la URV, que ofrece formaci\u00f3n al profesorado de secundaria sobre los conocimientos y la investigaci\u00f3n generados en las diferentes disciplinas acad\u00e9micas. Los cursos de verano est\u00e1n impartidos por profesorado de la URV y forma parte del programa Nexes, de colaboraci\u00f3n necesaria y positiva entre los estudiantes, profesorado, centros de secundaria y la Universidad.<\/p>\n<div class=\"panel rel\">\n<h5>Elementos relacionados<\/h5>\n<ul>\n<li class=\"link first last\"><a class=\"external\" href=\"http:\/\/www.urv.cat\/cae\/nexes\/Aprofundiments\/es_Aprofundiments.html\" target=\"_blank\" rel=\"external\">M\u00e1s informaci\u00f3n del programa &#8216;Aprofundundiments&#8217;<\/a><\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Durante este julio, la URV ha impartido por segunda edici\u00f3n cursos de actualizaci\u00f3n universitaria para el profesorado de secundaria sobre los conocimientos y la investigaci\u00f3n generados en las diferentes disciplinas acad\u00e9micas, lo que se denomina programa \u00abAprofundiments\u00bb<\/p>\n","protected":false},"author":11,"featured_media":9644,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[102,91,124,121,111],"tags":[1679,342,1684,1682,1683,1096],"class_list":["post-9649","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comciencia-es","category-docencia","category-portada-es","category-sociedad-y-cultura","category-urv-secundaria-es","tag-aprofundiments","tag-cae","tag-formacion","tag-nexes","tag-profesorado","tag-secundaria"],"acf":[],"_links":{"self":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/9649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/comments?post=9649"}],"version-history":[{"count":0,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/9649\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media\/9644"}],"wp:attachment":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media?parent=9649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/categories?post=9649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/tags?post=9649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}