{"id":9466,"date":"2014-07-30T12:28:34","date_gmt":"2014-07-30T10:28:34","guid":{"rendered":"http:\/\/ddurv.taller.fesomia.net\/?p=9466"},"modified":"2015-06-11T12:36:13","modified_gmt":"2015-06-11T10:36:13","slug":"desarrollan-un-sistema-ultrasensible-de-bajo-coste-y-portatil-para-la-deteccion-de-mercurio-en-el-agua","status":"publish","type":"post","link":"https:\/\/ddurv.taller.fesomia.net\/es\/desarrollan-un-sistema-ultrasensible-de-bajo-coste-y-portatil-para-la-deteccion-de-mercurio-en-el-agua\/","title":{"rendered":"Desarrollan un sistema ultrasensible, de bajo coste y port\u00e1til para la detecci\u00f3n de mercurio en el agua"},"content":{"rendered":"<p>Desde el inicio de la industrializaci\u00f3n, el mercurio se ha ido acumulando en el medio natural y sus efectos sobre la salud y el medio ambiente han sido una preocupaci\u00f3n que ha tomado fuerza desde la reciente incorporaci\u00f3n de una convenci\u00f3n mundial de la UNEP (United Nations Environment Programme) que busca monitorizar, controlar y reducir la contaminaci\u00f3n por mercurio a escala mundial.<\/p>\n<p>Actualmente existen sistemas que pueden hacer la monitorizaci\u00f3n de mercurio pero se trata de maquinaria pesada, cara y dif\u00edcil de hacer funcionar, ya que las personas que las tienen que utilizar necesitan tener un nivel de formaci\u00f3n integral. Adem\u00e1s, las muestras tambi\u00e9n necesitan pasar por un tratamiento qu\u00edmico antes de poder ser analizadas.<\/p>\n<p>El sistema, que han desarrollado investigadores australianos y tarraconenses, es muy competitivo en costes, f\u00e1cil de utilizar y de la medida de un tel\u00e9fono m\u00f3vil. Con una formaci\u00f3n muy b\u00e1sica, explica Llu\u00eds Marsal, uno de los investigadores del proyecto, \u00abse podr\u00eda llevar al r\u00edo o al lago y hacer una lectura de mercurio en pocos minutos\u00bb.<\/p>\n<p>El equipo ha dise\u00f1ado un material nanoporoso denominado al\u00famina an\u00f3dica nanoporosa y han desarrollado una estructura \u00f3ptica que modifica la propagaci\u00f3n de la luz. La superficie de los nanoporos -un nanoporo equivaldr\u00eda aproximadamente a mil millones de poros por cent\u00edmetro cuadrado- se ha modificado para que sea selectiva a los iones de mercurio. Cuando el agua pasa a trav\u00e9s de los nanoporos de la estructura, los iones de mercurio se adhieren a la superficie. Un sistema \u00f3ptico &#8211; denominado espectroscopia de reflexi\u00f3n &#8211; mide la cantidad de mercurio que se adhiere.<\/p>\n<p>Las pruebas que se han realizado durante el trabajo de investigaci\u00f3n han demostrado que, en una mezcla compleja con otros iones met\u00e1licos y muestras ambientales, este sensor puede detectar mercurio a niveles de 200 partes por mil millones (ppb). El trabajo que seguir\u00e1 a partir de ahora tratar\u00e1 de mejorar las se\u00f1ales \u00f3pticas para aumentar todav\u00eda m\u00e1s la sensibilidad.<\/p>\n<p>Los investigadores consideran que el rendimiento de detecci\u00f3n de este sistema es prometedor y, junto con el coste, la competitividad y la portabilidad hacen que sea una excelente alternativa potencial para las t\u00e9cnicas anal\u00edticas actuales. Esta t\u00e9cnica puede servir de base para los futuros sistemas de punto de an\u00e1lisis de la calidad del agua de supervisi\u00f3n in situ y puede ayudar a implementar mejores procesos de seguimiento de todo el mundo.<\/p>\n<p>El proyecto es una colaboraci\u00f3n de la Escuela de Ingenier\u00eda Qu\u00edmica de la Universidad de Adelaida (Australia) y la Universitat Rovira i Virgili. Los autores han sido los investigadores de la Universidad de Adelaida Tushar Kumeria, Dusan Losic y Abel Santos &#8211; que es el autor principal y que hab\u00eda sido doctorando de la URV-, y del Departamento de Ingenier\u00eda Electr\u00f3nica, El\u00e9ctrica y Autom\u00e1tica, de la Escuela T\u00e9cnica Superior de Ingenier\u00eda de la URV, Mahbubur Rahman Josep Ferr\u00e9-Borrull, Llu\u00eds Marsal.<\/p>\n<div class=\"panel rel\">\n<h5>Elementos relacionados<\/h5>\n<ul>\n<li class=\"link first last\"><a class=\"external\" href=\"http:\/\/pubs.acs.org\/doi\/abs\/10.1021\/am502882d\" target=\"_blank\" rel=\"external\">Applied Materials and Interfaces: Nanoporous Anodic Alumina Rugate Filters for Sensing of Ionic Mercury:Toward Environmental Point-of-Analysis Systems<\/a><\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se trata de un nuevo sistema ultrasensible, de bajo coste y port\u00e1til que permite detectar niveles bajos de mercurio en el agua a trav\u00e9s de un innovador sistema de detecci\u00f3n \u00f3ptico. Este sistema es fruto de un trabajo de investigaci\u00f3n, Nanoporous Anodic Alumina Rugate Filters for Sensing of Ionic Mercury: Toward Environmental Point-of-Analysis Systems que ha sido publicado a la revista cient\u00edfica ACS Applied Materiales and Interfaces<\/p>\n","protected":false},"author":11,"featured_media":9460,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[117,102,244,100,124],"tags":[1620,1621,1617],"class_list":["post-9466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-y-tecnologia","category-comciencia-es","category-escuela-tecnica-superior-de-ingenieria","category-investigacion","category-portada-es","tag-agua","tag-mercurio","tag-unep"],"acf":[],"_links":{"self":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/9466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/comments?post=9466"}],"version-history":[{"count":0,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/9466\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media\/9460"}],"wp:attachment":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media?parent=9466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/categories?post=9466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/tags?post=9466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}