{"id":9337,"date":"2014-09-19T13:13:09","date_gmt":"2014-09-19T11:13:09","guid":{"rendered":"http:\/\/ddurv.taller.fesomia.net\/?p=9337"},"modified":"2015-06-09T13:23:34","modified_gmt":"2015-06-09T11:23:34","slug":"los-ninos-que-consumen-leche-con-mas-proteinas-durante-el-primer-ano-tienen-tres-veces-mas-riesgo-de-sufrir-obesidad-que-los-que-toman-leche-materna","status":"publish","type":"post","link":"https:\/\/ddurv.taller.fesomia.net\/es\/los-ninos-que-consumen-leche-con-mas-proteinas-durante-el-primer-ano-tienen-tres-veces-mas-riesgo-de-sufrir-obesidad-que-los-que-toman-leche-materna\/","title":{"rendered":"Los ni\u00f1os que consumen leche con m\u00e1s prote\u00ednas durante el primer a\u00f1o tienen tres veces m\u00e1s riesgo de sufrir obesidad que los que toman leche materna"},"content":{"rendered":"<p>El estudio es el resultado de tres proyectos del 5\u00ba, 6\u00ba y 7\u00ba Programa Marco europeo: Childhood Obesity Project (CHOP), Early Nutrition Programming Project (EARNEST) y Long-term effects of early nutrition on later health (EarlyNutrition), en el que participa la Unidad de Investigaci\u00f3n en Pediatr\u00eda, Nutrici\u00f3n y Desarrollo Humano de la URV, al frente de la cual est\u00e1n los doctores Ricardo Closa y Joaqu\u00edn Escribano.<\/p>\n<p>El trabajo se ha publicado en la revista cient\u00edfica The American Journal of Clinical Nutrition y corresponde a los resultados de los estudios que se realizaron a los ni\u00f1os cuando ten\u00edan seis a\u00f1os.<\/p>\n<p>La ingesta de prote\u00ednas en los ni\u00f1os de cero a un a\u00f1o tiene un efecto en la obesidad futura. Los investigadores de este trabajo han comprobado que, a los seis a\u00f1os, se confirma la hip\u00f3tesis de que part\u00edan: los ni\u00f1os que han sido alimentados con leche artificial con alto contenido proteico tienen un riesgo tres veces superior de sufrir obesidad que los que han sido alimentados con leche materna, o bien con leche artificial con baja prote\u00edna.<\/p>\n<p>En este estudio, en el cual se ha hecho el seguimiento de 1.200 ni\u00f1as y ni\u00f1os de cinco pa\u00edses europeos desde su nacimiento, se hab\u00eda evidenciado el aumento del crecimiento corporal a los dos a\u00f1os de vida en aquellos que hab\u00edan recibido m\u00e1s prote\u00ednas a trav\u00e9s de la lactancia artificial los primeros a\u00f1os, un estudio publicado tambi\u00e9n a la revista The American Journal of Clinical Nutrition. Ahora, los resultados de los ni\u00f1os y de las ni\u00f1as correspondientes a los seis a\u00f1os -publicados en la misma revista cient\u00edfica- han confirmado que a los seis a\u00f1os, esta tendencia se mantiene. \u00abLos indicadores son m\u00e1s claros que a los dos a\u00f1os\u00bb, explica el doctor Ricardo Closa quien, junto con Joaqu\u00edn Escribano -los dos coordinadores de la Unidad de Investigaci\u00f3n en Pediatr\u00eda, Nutrici\u00f3n y Desarrollo Humano de la URV- participan en este trabajo de investigaci\u00f3n. Los \u00cdndices de Masa Corporal (IMC) ya muestran que los que han sido alimentados con leche artificial con altos contenidos de prote\u00ednas \u00abtienen casi tres veces m\u00e1s posibilidades de ser obesos a los seis a\u00f1os y, por lo tanto, un aumento del riesgo a sufrir problemas metab\u00f3licos en edad adulta\u00bb, explica el investigador.<\/p>\n<p>Los resultados de ahora confirman que recibir m\u00e1s prote\u00ednas durante el primer a\u00f1o deriva en un mayor peso durante los dos primeros a\u00f1os y m\u00e1s riesgo de sufrir obesidad a los seis. Esto se acompa\u00f1a, adem\u00e1s, de cambios en el metabolismo. No s\u00f3lo tienen un aumento de peso sino que sufren cambios hormonales que pueden favorecer alteraciones metab\u00f3licas en un futuro. El aumento de riesgo se comprueba, apuntan, extrayendo todos los factores que puedan interferir: h\u00e1bitos de vida, actividad f\u00edsica, alimentaci\u00f3n posterior, etc. Es decir, en el estudio se a\u00edslan los factores que puedan confundir los resultados. Por otro lado, durante el seguimiento de los ni\u00f1os se estudia no s\u00f3lo la implicaci\u00f3n de las prote\u00ednas en la obesidad futura, sino tambi\u00e9n su papel en el desarrollo de los \u00f3rganos y a nivel metab\u00f3lico. Algunos de estos efectos est\u00e1n publicados en revistas cient\u00edficas fruto de los trabajos de los mismos investigadores.<\/p>\n<figure id=\"attachment_9335\" aria-labelledby=\"figcaption_attachment_9335\" class=\"wp-caption alignnone\" style=\"width: 700px\"><a href=\"http:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/140918_estud_obes-2_Ok.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-9335 size-full\" src=\"http:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/140918_estud_obes-2_Ok.jpg\" alt=\"La Unitat de Recerca en Pediatria, Nutrici\u00f3 i Desenvolupament Hum\u00e0 de la URV, forma part del projecte.\" width=\"700\" height=\"525\" srcset=\"https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/140918_estud_obes-2_Ok.jpg 700w, https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/140918_estud_obes-2_Ok-300x225.jpg 300w, https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/140918_estud_obes-2_Ok-384x287.jpg 384w, https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/140918_estud_obes-2_Ok-800x600.jpg 800w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><figcaption id=\"figcaption_attachment_9335\" class=\"wp-caption-text\">La Unidad de Investigaci\u00f3n en Pediatr\u00eda, Nutrici\u00f3n y Desarrollo Humano de la URV, forma parte del projecto.<\/figcaption><\/figure>\n<p>Los resultados de ahora \u00abtienen una trascendencia muy alta a nivel de salud p\u00fablica\u00bb, explica el doctor, que a\u00f1ade que las casas comerciales han ido por delante de las recomendaciones de las agencias europeas y \u00abya limitan las prote\u00ednas\u00bb. En Europa han bajado los \u00edndices permitidos de prote\u00ednas en la leche, \u00abpero esta investigaci\u00f3n tendr\u00eda que hacer cambiar las recomendaciones de salud\u00bb. Con los resultados en la mano, los investigadores recomiendan que las leches artificiales tengan 1,8 gramos de prote\u00ednas por cien calor\u00edas mientras que est\u00e1 aceptado pr\u00e1cticamente el doble, 3,5 gramos, y \u00abtodav\u00eda tendr\u00eda que bajar m\u00e1s\u00bb, apuntan los investigadores.<\/p>\n<p>El trabajo de investigaci\u00f3n se enmarca en el Childhood Obesity Project y recibe financiaci\u00f3n actualmente a trav\u00e9s del proyecto Long-term effects of early nutrition on later health (EarlyNutrition). El proyecto recibe una ayuda de 8,96 millones de euros del 7\u00ba Programa Marco de la Comisi\u00f3n Europea y lo llevan a cabo equipos de investigaci\u00f3n de toda Europa, Australia y Estados Unidos.<\/p>\n<h5>Estudio de la ingesta de prote\u00ednas durante el segundo a\u00f1o de vida<\/h5>\n<p>Se ha comprobado que la ingesta de prote\u00ednas precoz tiene un efecto a la larga, puesto que afectan el fenotipo. Se ha detectado que se consumen demasiadas durante los primeros meses y que este hecho tiene consecuencias metab\u00f3licas posteriores, seg\u00fan los investigadores, que piensan que el efecto de las prote\u00ednas durante el primer a\u00f1o se podr\u00eda extender tambi\u00e9n al segundo a\u00f1o de vida. Este hecho tiene tanta importancia que ahora har\u00e1n un nuevo estudio con investigadores de Alemania y Espa\u00f1a para comprobar qu\u00e9 efectos tiene la ingesta de una cantidad de prote\u00ednas elevada durante el segundo a\u00f1o de vida, en la obesidad posterior. \u00abTenemos claro que tenemos que encontrar las causas para prevenir la obesidad porque el tratamiento es poco efectivo y los cambios metab\u00f3licos son precoces\u00bb. Se estudiar\u00e1n 2.000 ni\u00f1os de los cuales ahora se empezar\u00e1 a hacer la recogida y el seguimiento. La alimentaci\u00f3n el segundo a\u00f1o es libre y complementaria y la leche es el alimento que marca la diferencia en la aportaci\u00f3n proteica.<\/p>\n<h5>Elementos relacionados<\/h5>\n<ul>\n<li><a href=\"http:\/\/www.project-earlynutrition.eu\/eneu\/\" target=\"_blank\">P\u00e1gina web del proyecto<\/a><\/li>\n<li><a href=\"http:\/\/ajcn.nutrition.org\/content\/99\/5\/1041\" target=\"_blank\">Lower protein content in infant formula reduces BMI and obesity risk at school age: follow-up of a randomized trial<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Lo confirma el resultado de la comparativa de 1.200 ni\u00f1as y ni\u00f1os de cinco pa\u00edses europeos que durante el primer a\u00f1o de vida han sido alimentados con leche materna y con leche artificial de alto y bajo contenido proteico<\/p>\n","protected":false},"author":11,"featured_media":9332,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[101,102,100,124,120],"tags":[1606,1607,1608,1610],"class_list":["post-9337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-centros-de-investigacion-urv","category-comciencia-es","category-investigacion","category-portada-es","category-salud","tag-joaquin-escribano","tag-ricardo-closa","tag-the-american-journal-of-clinical-nutrition","tag-unidad-de-investigacion-en-pediatria-nutricion-y-desarrollo-humano"],"acf":[],"_links":{"self":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/9337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/comments?post=9337"}],"version-history":[{"count":0,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/9337\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media\/9332"}],"wp:attachment":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media?parent=9337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/categories?post=9337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/tags?post=9337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}