{"id":8417,"date":"2014-11-19T11:03:47","date_gmt":"2014-11-19T11:03:47","guid":{"rendered":"http:\/\/ddurv.taller.fesomia.net\/lequip-de-la-urv-guanya-la-tercera-edicio-del-torneig-interuniversitari-rym-2\/"},"modified":"2015-05-08T11:15:13","modified_gmt":"2015-05-08T11:15:13","slug":"lequip-de-la-urv-guanya-la-tercera-edicio-del-torneig-interuniversitari-rym","status":"publish","type":"post","link":"https:\/\/ddurv.taller.fesomia.net\/es\/lequip-de-la-urv-guanya-la-tercera-edicio-del-torneig-interuniversitari-rym\/","title":{"rendered":"El equipo de la URV gana la tercera edici\u00f3n del torneo interuniversitario RYM"},"content":{"rendered":"<p>Los estudiantes de la URV Eudald Llaurad\u00f3, de <em>Biotecnolog\u00eda<\/em>, y Miguel \u00c1ngel Pollino, de <em>Bioqu\u00edmica y biolog\u00eda molecular<\/em>, ganaron el martes 18 de noviembre la final del III Torneo interuniversitario\u00a0<em>Research your mind<\/em>\u00a0(RYM), en el qual participan las universidades catalanas. Los tarraconenses se impusieron a seis equipos m\u00e1s de universidades de Barcelona y de Lleida. La actividad, que se enmarca en la Semana de la Ciencia, se celebr\u00f3 en el Mobile World Centre en Barcelona. Como premio, los ganadores se llevaron dos tabletas\u00a0Samsung y dos altavoces port\u00e1tiles Sony.<\/p>\n<p><em>Research your mind<\/em> (RYM) es un juego sobre ciencia, de preguntas y respuestas, que pretende promover esta disciplina entre los j\u00f3venes de forma educativa y l\u00fadica. En la\u00a0competici\u00f3n, impulsada por la Fundaci\u00f3 Catalana per a la Recerca i la Innovaci\u00f3 (FCRi), cada universidad puede presentar un equipo formado por dos estudiantes de primer curso de grado. Este a\u00f1o es la primera vez que un equipo de la URV participa en este certamen. Tambi\u00e9n tomaron parte las universidades de Lleida, de Barcelona, Polit\u00e8cnica de Catalunya, Aut\u00f2noma de Barcelona, Ramon Llull y Abat\u00a0Oliba.<\/p>\n<figure id=\"attachment_8413\" aria-labelledby=\"figcaption_attachment_8413\" class=\"wp-caption alignnone\" style=\"width: 607px\"><a href=\"http:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/05\/RYM_14-15.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8413\" src=\"http:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/05\/RYM_14-15.jpg\" alt=\"\" width=\"607\" height=\"455\" srcset=\"https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/05\/RYM_14-15.jpg 700w, https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/05\/RYM_14-15-300x225.jpg 300w, https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/05\/RYM_14-15-384x287.jpg 384w, https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/05\/RYM_14-15-800x600.jpg 800w\" sizes=\"auto, (max-width: 607px) 100vw, 607px\" \/><\/a><figcaption id=\"figcaption_attachment_8413\" class=\"wp-caption-text\">Los estudiantes de la URV Eudald Llaurad\u00f3 y Miguel \u00c1ngel Pollino, durante el torneo interuniversitario RYM.<\/figcaption><\/figure>\n<p>El juego cient\u00edfico RYM est\u00e1 integrado por unas 400 preguntas sobre diferentes \u00e1mbitos de la ciencia (salud; alimentaci\u00f3n, agricultura y biotecnolog\u00eda; nanociencias, nanotecnolog\u00edas y tecnolog\u00edas de la informaci\u00f3n y comunicaci\u00f3n; energ\u00eda y medio ambiente; transportes, seguridad y espacio; y ciencias humanas y sociales). En esta edici\u00f3n, de hecho, se estrenaron 100 nuevas preguntas relacionadas con el <em>Tricentenari<\/em> y la conmemoraci\u00f3n del Centenario de la Mancomunidad de Catalu\u00f1a. El equipo de divulgadores del programa radiof\u00f3nico <em>Pa ci\u00e8ncia la nostra<\/em> (R\u00e0dio Sants) condujo el acto.<\/p>\n<p>Coincidiendo con este torneo interuniversitario, la FCRi puso en marcha un concurso en l\u00ednea tambi\u00e9n acerca del juego de ciencia RYM. Hasta el 4 de diciembre, los estudiantes pueden jugar a trav\u00e9s del web\u00a0<a class=\"external\" href=\"http:\/\/www.rym.cat\/\" target=\"_blank\" rel=\"external\">www.rym.cat<\/a> y aspirar a ganar varios premios. Este a\u00f1o es la 19\u00aa edici\u00f3n de la Semana de la Ciencia, que se alargar\u00e1 hasta el domingo.<\/p>\n<div class=\"panel rel\">\n<h5>Elementos relacionados<\/h5>\n<ul>\n<li class=\"link first last\"><a class=\"external\" href=\"http:\/\/www.rym.cat\/\" target=\"_blank\" rel=\"external\">Juego &#8216;Research your mind&#8217; (RYM)<\/a><\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8216;Research your mind&#8217; (RYM) es un juego de preguntas y respuestas sobre ciencia en el cual pueden participar las universidades catalanas. Este certamen, que se enmarca en la Semana de la Ciencia, se disput\u00f3 en el Mobile World Centre en Barcelona<\/p>\n","protected":false},"author":11,"featured_media":8410,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[117,102,87,100,124],"tags":[1368,1367,1366,1347],"class_list":["post-8417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-y-tecnologia","category-comciencia-es","category-estudiantes","category-investigacion","category-portada-es","tag-biotecnologia","tag-fcri","tag-research-your-mind","tag-semana-de-la-ciencia"],"acf":[],"_links":{"self":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/8417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/comments?post=8417"}],"version-history":[{"count":0,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/8417\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media\/8410"}],"wp:attachment":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media?parent=8417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/categories?post=8417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/tags?post=8417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}