{"id":7499,"date":"2015-04-08T12:40:08","date_gmt":"2015-04-08T12:40:08","guid":{"rendered":"http:\/\/ddurv.taller.fesomia.net\/presenten-una-guia-per-garantir-la-proteccio-de-les-dones-victimes-de-violencia-de-genere-a-europa-2\/"},"modified":"2015-04-09T11:02:10","modified_gmt":"2015-04-09T11:02:10","slug":"presenten-una-guia-per-garantir-la-proteccio-de-les-dones-victimes-de-violencia-de-genere-a-europa","status":"publish","type":"post","link":"https:\/\/ddurv.taller.fesomia.net\/es\/presenten-una-guia-per-garantir-la-proteccio-de-les-dones-victimes-de-violencia-de-genere-a-europa\/","title":{"rendered":"Elaboran una gu\u00eda para garantizar la protecci\u00f3n de las mujeres v\u00edctimas de violencia de g\u00e9nero en Europa"},"content":{"rendered":"<p>La diversidad de sistemas jur\u00eddicos de cada estado miembro de la Uni\u00f3n Europea genera conflictos y dificultades a la hora de cumplir con las disposiciones de la Directiva Europea que tiene que garantizar que las mujeres tengan la misma protecci\u00f3n en casos de violencia de g\u00e9nero en cualquiera de los estados miembros de la Uni\u00f3n. Con el objetivo de conocer qu\u00e9 medidas de protecci\u00f3n existen para garantizar la protecci\u00f3n de las v\u00edctimas, los investigadores del proyecto europeo <a href=\"www.epogender.eu\">Epogender<\/a> elaboraron un primer manual que incluye una recopilaci\u00f3n de la legislaci\u00f3n y las pr\u00e1cticas de los Estados miembros afectados por la Directiva relativa a las medidas de protecci\u00f3n para las v\u00edctimas de violencia de g\u00e9nero y un segundo manual donde se presenta un an\u00e1lisis de los estados estudiados y se sugieren indicadores para lograr una transposici\u00f3n correcta y eficaz de la Directiva, poniendo de relieve los obst\u00e1culos y dificultades que puedan surgir en el proceso. El proyecto ha hecho frente a la diversidad legal de los Estados miembros, que se a\u00f1ade a la dificultad de trabajar con conceptos que aparentemente tienen el mismo significado -como violencia dom\u00e9stica, o violencia de g\u00e9nero, o violencia familiar- pero que en la pr\u00e1ctica pueden diferir de un estado a otro.<\/p>\n<p>La Directiva 2011\/99 \/ EU, sobre la Orden Europea de Protecci\u00f3n pretende proteger a las v\u00edctimas cuando circulen o se desplacen por la Uni\u00f3n Europea y se centra en las tres medidas de protecci\u00f3n m\u00e1s comunes: la prohibici\u00f3n de acercarse a los lugares donde la v\u00edctima reside o frecuenta, el establecimiento de una distancia m\u00ednima entre la v\u00edctima y el agresor y la prohibici\u00f3n de entrar en contacto con la persona protegida. De hecho, la Directiva no obliga a los Estados miembros a modificar su normativa interna, sino que instaura un mecanismo de cooperaci\u00f3n judicial que obliga a ofrecer a las v\u00edctimas una protecci\u00f3n equivalente a la que dispone en su estado de origen, pero una protecci\u00f3n que a su vez depende de las medidas disponibles en el ordenamiento interno del estado de destino. La gu\u00eda final ordena los estados en tres modelos en funci\u00f3n de la naturaleza de las medidas de protecci\u00f3n que aplican; as\u00ed, por ejemplo, en Espa\u00f1a se aplican s\u00f3lo medidas de tipo penal, en Austria y Alemania, medidas s\u00f3lo civiles, y el resto de pa\u00edses tienen medidas mixtas.<\/p>\n<p>Teniendo en cuenta las peculiaridades de cada estado, el manual presenta recomendaciones o indicadores que deben permitir hacer efectiva la Directiva. Se recomienda, por ejemplo, que las medidas de protecci\u00f3n se adopten tanto antes de iniciar un proceso como despu\u00e9s, una vez dictada la sentencia; que se aproxime la duraci\u00f3n de las medidas de protecci\u00f3n entre los diversos estados; que se establezcan sanciones en casos de rotura de las medidas de protecci\u00f3n, -ya que algunos estados no lo sancionen-, o que se valore c\u00f3mo deben ser estas sanciones. En cuanto a la v\u00edctima, se recomienda que los estados se comprometan a proporcionar la m\u00e1xima informaci\u00f3n sobre las medidas de protecci\u00f3n disponibles, sobre la situaci\u00f3n procesal del agresor, -que puede ser un indicador del nivel de riesgo en que se encuentra la v\u00edctima-, ya proporcionar una asistencia jur\u00eddica gratuita, entre otros.<\/p>\n<p>El trabajo ha sido presentado en diferentes foros de profesionales implicados en el tema jueces, fiscales, asociaciones de mujeres, polic\u00edas, docentes-, para darle difusi\u00f3n con el objetivo de que entre todos contribuyan a garantizar un mismo nivel de protecci\u00f3n a las mujeres que se desplacen por la Uni\u00f3n Europea. Este segundo manual, que marca el punto final de los dos a\u00f1os de proyecto, se present\u00f3 en Bruselas el pasado 18 de marzo, en un acto donde intervinieron miembros del equipo de trabajo internacional, integrado por cuatro socios: las dos universidades catalanas coordinadoras -la Universitat Rovira i Virgili i la Universitat Aut\u00f2noma de Barcelona- , la Universidad de Szczecin (Polonia) y una asociaci\u00f3n de jueces de Bulgaria. Una vez culminado el proyecto, el grupo de investigadores de la URV ha presentado un nuevo proyecto a la Comisi\u00f3n Europea para estudiar y mejorar los mecanismos de cooperaci\u00f3n judicial en los casos de violencia de g\u00e9nero.<\/p>\n<p>Actualmente se calcula que hay unas 100.000 \u00f3rdenes de protecci\u00f3n a v\u00edctimas de violencia de g\u00e9nero en Europa, 6.000 de las cuales en Espa\u00f1a. Y un 32% del total de estas \u00f3rdenes de protecci\u00f3n las han solicitado mujeres extranjeras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es el resultado del proyecto europeo Epogender, que tiene el objetivo de impulsar la transposici\u00f3n de la Directiva relativa a la Orden Europea de Protecci\u00f3n para las v\u00edctimas de violencia de g\u00e9nero a buena parte de los estados miembros de la UE. El proyecto est\u00e1 coordinado y dirigido por Laura Rom\u00e1n (URV) y Teresa Freixes (UAB) <\/p>\n","protected":false},"author":12,"featured_media":7493,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[102,252,83,124],"tags":[1084,1085],"class_list":["post-7499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comciencia-es","category-facultad-ciencias-juridicas","category-general-es","category-portada-es","tag-violencia-de-genere-es","tag-violencia-de-genero"],"acf":[],"_links":{"self":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/7499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/comments?post=7499"}],"version-history":[{"count":0,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/7499\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media\/7493"}],"wp:attachment":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media?parent=7499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/categories?post=7499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/tags?post=7499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}