{"id":7144,"date":"2015-03-10T07:27:04","date_gmt":"2015-03-10T07:27:04","guid":{"rendered":"http:\/\/ddurv.taller.fesomia.net\/dos-projectes-deducacio-i-un-docupacio-obtenen-ajuts-a-la-recerca-del-programa-recercaixa-2014-2\/"},"modified":"2015-03-22T19:22:45","modified_gmt":"2015-03-22T19:22:45","slug":"dos-projectes-deducacio-i-un-docupacio-obtenen-ajuts-a-la-recerca-del-programa-recercaixa-2014-2","status":"publish","type":"post","link":"https:\/\/ddurv.taller.fesomia.net\/es\/dos-projectes-deducacio-i-un-docupacio-obtenen-ajuts-a-la-recerca-del-programa-recercaixa-2014-2\/","title":{"rendered":"Dos proyectos de educaci\u00f3n y uno de empleo de la URV obtienen ayudas a la investigaci\u00f3n del programa RecerCaixa 2014"},"content":{"rendered":"<p>RecerCaixa es un programa de la Obra Social \u00abla Caixa\u00bb, con la colaboraci\u00f3n de la Associaci\u00f3 Catalana d&#8217;Universitats P\u00fabliques (ACUP),\u00a0 para apoyar a la investigaci\u00f3n de excelencia en Catalu\u00f1a. En un acto en Cosmocaixa se han entregado las 26 nuevas ayudas de la convocatoria 2014 del programa RecerCaixa, para llevar a cabo proyectos de excelencia en los campos de las ciencias sociales, las humanidades y las ciencias de la salud, a los que se destinan 2 milions d&#8217;euros.<\/p>\n<p>Entre los 26 proyectos seleccionados de los 221 presentados, figuran los tres conseguidos per investigadores de la URV. Son: del \u00e1rea de Educaci\u00f3n, el proyecto \u00abEsfuerzo, informaci\u00f3n y expectativas como determinantes del \u00e9xit acad\u00e9mico: un an\u00e1lisis emp\u00edrico en el contexto de la educaci\u00f3n secundaria\u00bb, del profesor Luis D\u00edaz, del Departamento de Econom\u00eda. En este proyecto se investigan los determinantes y las consecuencias del\u00a0 abandono escolar prematuro en Catalu\u00f1a, centrados en aspectes menos estudiados como el v\u00ednculo entre el rendimiento escolar y factores individuales subjectivos, generalmente no observables como la motivaci\u00f3n, las expectativas y las creencias sobre el mercado de trabajo.<\/p>\n<p>El segundo proyecto de Educaci\u00f3n \u00e9s \u00abFormaci\u00f3n profesional y pymes: el reto de la innovaci\u00f3n\u00bb, del profesor Ignasi Brunet, del Departamento de Gesti\u00f3n de Empresas. La investigaci\u00f3n se propone estudiar la adecuaci\u00f3n de la formaci\u00f3n en innovaci\u00f3n que los centros de FP ofrecen a sus alumnos a\u00a0 las exigencias en innovaci\u00f3n que las empresas reclaman a sus trabajadores t\u00e9cnicos; y a partir de esta formaci\u00f3n recibida, analizar qu\u00e9 contribuci\u00f3n pueden hacer los empleados con formaci\u00f3n en FP a la innovaci\u00f3n en las pymes.<\/p>\n<p>El tercer proyecto seleccionado es de ocupaci\u00f3n y de igualdad de g\u00e9nero, y se titula: \u00abHombres cuidadores: retos y oportunidades para reducir las desigualdades de g\u00e9nero y afrontar las nuevas necesidades de cuidados\u00bb. Lo han presentado la investigadora Dolors Comas d&#8217;Argemir, del Departamento de Antropolog\u00eda, Filosof\u00eda y Trabajo Social de la URV, y Diana Marre de la UAB. La implicaci\u00f3n de los hombres en los trabajos de cuidados es un reto pendiente en t\u00e9rminos de igualdad de g\u00e9nero, pero tambi\u00e9n a la hora de afrontar el considerable incremento de las situaciones de dependencia vinculadas a la edad y las necesidades de cuidado en la sociedad actual. Se estudian los cambios y las resistencias, y se identifican las barreras culturales y de oportunidad que dificultan la implicaci\u00f3n de los hombres en estas tareas, tanto en las remuneradas com en las no remuneradas.<\/p>\n<p>La Obra Social la Caixa ha renovado su compromiso con la investigaci\u00f3n a trav\u00e9s del programa RecerCaixa para el per\u00edodo 2015-19, con una inversi\u00f3n prevista de 9 millones de euros. En total, desde el inicio del programa e incluyendo la convocataria 2014 ya se han financiado 120 proyectos de investigaci\u00f3n, y la inversi\u00f3n hasta el 2019 sumar\u00e1 18 millones de euros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los profesores Luis D\u00edaz, Dolors Comas y Ignasi Brunet son los responsables de los proyectos. La Obra Social la Caixa y la ACUP han entregado en CosmoCaixa en Barcelona las nuevas ayudas a la investigaci\u00f3n de la convocatoria 2014<\/p>\n","protected":false},"author":12,"featured_media":7156,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[101,102,118,251,234,253,121],"tags":[303,1000,996,997,998],"class_list":["post-7144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-centros-de-investigacion-urv","category-comciencia-es","category-economia-y-empresa","category-facultad-ciencias-educacion-psicologia","category-facultat-deconomia-i-empresa-es","category-facultad-de-letras","category-sociedad-y-cultura","tag-acup-es","tag-dolors-comas","tag-ignasi-brunet-es","tag-luis-diaz-es","tag-recercaixa-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/7144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/comments?post=7144"}],"version-history":[{"count":0,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/7144\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media\/7156"}],"wp:attachment":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media?parent=7144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/categories?post=7144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/tags?post=7144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}