{"id":7132,"date":"2015-03-12T07:48:38","date_gmt":"2015-03-12T07:48:38","guid":{"rendered":"http:\/\/ddurv.taller.fesomia.net\/cientifics-darreu-del-mon-exposen-a-la-urv-els-ultims-avencos-sobre-canvi-climatic-a-la-peninsula-iberica-2\/"},"modified":"2015-10-06T10:46:23","modified_gmt":"2015-10-06T08:46:23","slug":"cientificos-de-todo-del-mundo-exponen-en-la-urv-los-ultimos-avances-sobre-cambio-climatico-en-la-peninsula-iberica","status":"publish","type":"post","link":"https:\/\/ddurv.taller.fesomia.net\/es\/cientificos-de-todo-del-mundo-exponen-en-la-urv-los-ultimos-avances-sobre-cambio-climatico-en-la-peninsula-iberica\/","title":{"rendered":"Cient\u00edficos de todo del mundo exponen en la URV los \u00faltimos avances sobre cambio clim\u00e1tico en la pen\u00ednsula Ib\u00e9rica"},"content":{"rendered":"<p>Los \u00faltimos avances en la detecci\u00f3n y estudio del cambio clim\u00e1tico en la pen\u00ednsula Ib\u00e9rica y las \u00faltimas proyecciones de c\u00f3mo evolucionar\u00e1 el clima en los pr\u00f3ximos a\u00f1os se expondr\u00e1n esta setmana en el Simposio Internacional CLIMA-ES 2015: Avances en la detecci\u00f3n i proyecciones del cambio clim\u00e1tico en el Estado espa\u00f1ol, del 11 al 13 de marzo del 2015 en el Campus Terres de l&#8217;Ebre de la URV.<\/p>\n<p>Organizado por el C3 (Centre de Canvi Clim\u00e0tic) de la URV, en este encuentro participar\u00e1n los principales expertos en cambio clim\u00e1tico espa\u00f1oles e internacionales y se har\u00e1n p\u00fablicos los \u00faltimos avances y proyecciones sobre el cambio clim\u00e1tico en el Estado, que se han producido desde la publicaci\u00f3n del quinto y \u00faltimo informe del IPCC (el Grupo Intergubernamental de Expertos sobre Cambio Clim\u00e1tico), elaborado en el 2013. Es la primera vez que en el Estado espa\u00f1ol todos los organismos con inter\u00e9s y responsabilidad sobre el cambio clim\u00e1tico &#8211; AEMET (Agencia Estatal de Meteorolog\u00eda), OECC (Oficina Espa\u00f1ola de Cambio Clim\u00e1tico), los Puertos del Estado, IEO (Instituto Estatal de Oceanograf\u00eda), AEC (Asociaci\u00f3n Espa\u00f1ola de Climatolog\u00eda), AME (Asociaci\u00f3n Meteorol\u00f3gica Espa\u00f1ola), Comit\u00e9 Nacional CLIVAR-ES y Comit\u00e8 Nacional WCRP-ES- organizan conjuntamente y apoyan una activitat integradora de discusi\u00f3n cient\u00edfica como \u00e9sta.\u00a0 El objetivo final es la elaboraci\u00f3n de un informe sobre el pasado, el presente y el futuro del clima en Espa\u00f1a, al estilo de los informes del IPCC.<\/p>\n<p>En este encuentro, un total de m\u00e1s de 100 expertos presentar\u00e1n 9 ponencias invitadas y\u00a0 109 contribuciones cient\u00edficas, de las que 45 son presentaciones orals y 64 en formato p\u00f3ster. Se han inscrito un centenar de personas procedentes principalmente del Estado y tambi\u00e9n de Francia, Alemania, Portugal, Italia y de Mali.<\/p>\n<p>El Simposio se ha estructurado en seis sesiones que abordaran estas cuestiones: reconstrucciones paleoclim\u00e1ticas en la pen\u00ednsula Ib\u00e9rica; observaci\u00f3n clim\u00e1tica y t\u00e8cnicas de reconstrucci\u00f3n del clima, variabilidad atmosf\u00e9rica en el sector euroatl\u00e1ntico; variabilidad oce\u00e1nica y variaciones del nivel del mar en la costa peninsular y archipi\u00e9lagos. Los cambios y tendencias observados en los \u00faltimos a\u00f1os; y las proyecciones clim\u00e1ticas regionales en el Estado espa\u00f1ol para los pr\u00f3ximos 30 anys, desde el punto de vista de la atm\u00f3sfera y del medio\u00a0 marino. As\u00ed, hay comunicaciones sobre la evoluci\u00f3n del delta del Ebro desde su formaci\u00f3n hace 8.000 a\u00f1os y desde hace 200 a\u00f1os, cuando empez\u00f3 a ser colonizado; sobre el incremento de la temperatura del r\u00edo Ebro o sobre el efecto del cambio clim\u00e1tico en el cultivo del arroz. Tambi\u00e9n se examinar\u00e1n los \u00faltimos datos sobre el clima del pasado que se hayan podido extraer analizando estalagmitas y estalactitas, los anillos de los \u00e1rboles o los sedimentos de r\u00edos y lagos. Y tambi\u00e9n la extracci\u00f3n de datos clim\u00e1ticos a partir de rogativas (plegarias para pedir que llueva).<\/p>\n<p>Entre las ponencias previstas hay que destacar: La Reconstrucci\u00f3n y simulaci\u00f3n del clima: desde la escala global a la regional, que ir\u00e1 a cargo de Fidel Gonz\u00e1lez-Rouco, del Instituto de Geociencias de la Universidad Complutense de Madrid y del CSIC;\u00a0 Variabilidad clim\u00e1tica y oce\u00e1nica en aguas atl\u00e1nticas espa\u00f1olas. Cambio y tendencias observadas en las \u00faltimas d\u00e9cadas, que impartir\u00e1 C\u00e9sar Gonz\u00e1lez-Pola del Instituto Espa\u00f1ol de Oceanograf\u00eda (IEO); o Proyecciones regionales del clima de la Pen\u00ednsula Ib\u00e9rica (2060-2100), a cargo de Manuel de Castro, de la Universidad de Castilla la Mancha. Tambi\u00e9n merecen una atenci\u00f3n especial las investigaciones realizadas por el C3 de la URV, centradas en la recuperaci\u00f3n i calidad de les series de datos clim\u00e1ticos.<\/p>\n<p>Para acabar el Simposio se han organizado dos actos paralelos, uno centrado en las oportunidades, limitaciones y retos para la provisi\u00f3n de servicios clim\u00e1ticos, y una mesa redonda sobre la comunicaci\u00f3n del cambio clim\u00e1tico a la sociedad y sus retos.<\/p>\n<p>En el primer acto intervendr\u00e1n destacados expertos del Estado y de Europa como Fernando Belda, director de la AEMET o Paco Doblas-Reyes, director de Barcelona Supercomputing\u00a0 Center, y se debatir\u00e1 sobre los retos y las oportunidades para ofrecer servicios clim\u00e1ticos orientados a sectores espec\u00edficos de actividad com la salud, el agua o la energ\u00eda.<\/p>\n<p>El objetivo de la mesa redonda es explorar qu\u00e9 hay que hacer para proporcionar a la sociedad una informaci\u00f3n rigurosa, equilibrada y cre\u00edble sobre el cambio clim\u00e1tico. Como ponentes se ha invitado a nombres destacados de la comunicaci\u00f3n:\u00a0 Antonio Cerrillo de \u00abLa Vanguardia\u00bb;\u00a0 Jos\u00e9 Luis Pi\u00f1uel y Rogelio Fernandez Reyes, de la Universidad Complutense de Madrid;\u00a0 Pablo Meira de la Universidad de Santiago de Compostela; Florenci Rey\u00a0 de la cadena SER; y Ferran Puig de la web Ustednoselocree.com, especializada en divulgaci\u00f3n cient\u00edfica sobre el cambio clim\u00e1tico. I tambi\u00e9n habr\u00e1 un acto paralelo sobre servicios clim\u00e1ticos, en el que participar\u00e1n investigadores del IC3 (Institut Catal\u00e0 de Ci\u00e8ncies del Clima) y responsables de l&#8217;AEMET. Este acto va dirigido a los servicios clim\u00e1ticos que elaboran y ofrecen informaci\u00f3n que puede ser muy \u00fatil a muchos sectores de la sociedad.<\/p>\n<p>La inauguraci\u00f3n del Simposio, este mi\u00e9rcoles 11 de marzo, ir\u00e1 a cargo de Carmen Vela, secretaria de Estado de Investigaci\u00f3n, Desarrollo e Innovaci\u00f3n; Fernando Belda, director de Producci\u00f3n e Infraestructuras\u00a0 d&#8217;AEMET;\u00a0 Josep Anton Ferr\u00e9, rector de la URV; y Ferran Bel, alcalde de Tortosa. Una vez finalizado el Simposio se iniciar\u00e1n los trabajos para elaborar el Informe, que se prev\u00e9 que est\u00e9 acabado en un a\u00f1o y que se presentar\u00e1 a la sociedad espa\u00f1ola.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La evoluci\u00f3n del delta del Ebro en los \u00faltimos a\u00f1os o los efectos del cambio clim\u00e1tico en el cultivo  del arroz, son algunos de los temas que se tratar\u00e1n en el Simposio Internacional CLIMA-ES 2015, que tednr\u00e1 lugar en el Campus Terres de l\u2019Ebre de la URV<\/p>\n","protected":false},"author":12,"featured_media":6988,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[101,117,102,256,140,121],"tags":[445,449,755,446,775],"class_list":["post-7132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-centros-de-investigacion-urv","category-ciencia-y-tecnologia","category-comciencia-es","category-facultad-turismo-geografia","category-medio-ambiente-urv","category-sociedad-y-cultura","tag-c3-es","tag-cambio-climatico-es","tag-campus-terres-de-lebre-es","tag-canvi-climatic-es","tag-clima-es-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/7132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/comments?post=7132"}],"version-history":[{"count":0,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/7132\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media\/6988"}],"wp:attachment":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media?parent=7132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/categories?post=7132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/tags?post=7132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}