{"id":6125,"date":"2015-01-07T16:31:04","date_gmt":"2015-01-07T16:31:04","guid":{"rendered":"http:\/\/ddurv.taller.fesomia.net\/josep-lluis-domingo-editor-en-cap-de-food-and-chemical-toxicology-2\/"},"modified":"2015-05-22T11:03:32","modified_gmt":"2015-05-22T09:03:32","slug":"josep-lluis-domingo-editor-en-cap-de-food-and-chemical-toxicology","status":"publish","type":"post","link":"https:\/\/ddurv.taller.fesomia.net\/es\/josep-lluis-domingo-editor-en-cap-de-food-and-chemical-toxicology\/","title":{"rendered":"Josep Llu\u00eds Domingo, editor jefe de \u00abFood and chemical toxicology\u00bb"},"content":{"rendered":"<p>El investigador forma parte del reducido n\u00famero de profesores universitarios de Espa\u00f1a que son coeditores o editores de una revista cient\u00edfica internacional.<\/p>\n<div align=\"left\">\n<p>La revista <a href=\"http:\/\/www.journals.elsevier.com\/food-and-chemical-toxicology\/\"><span style=\"color: #0066cc;\">\u00abFood and chemical toxicology\u00bb<\/span><\/a> recibe cada a\u00f1o 2.500 art\u00edculos cient\u00edficos, que quieren ser publicados. Tambi\u00e9n desde el 1 de marzo de 2014 es\u00a0editor jefe de la revista cient\u00edfica <a href=\"http:\/\/www.journals.elsevier.com\/environmental-research\/\"><span style=\"color: #0066cc;\">\u00abEnvironmental Research\u00bb, <\/span><\/a>del grupo Elsevier. Esta publicaci\u00f3n recibe 1.500 art\u00edculos anuales.<\/p>\n<p>Josep Llu\u00eds Domingo (Tortosa, 1951) es doctor en Toxicolog\u00eda por la UB (1982) y catedr\u00e1tico de la URV desde el a\u00f1o 1991, donde ejerce la docencia en la Facultad de Medicina y Ciencias de la Salud. Es fundador del Laboratorio de Toxicolog\u00eda y Salud Medioambiental de la URV y Profesor Distinguido de la URV (2006) e impulsor del centro TecnATox.<\/p>\n<p>El profesor de la URV est\u00e1 entre los investigadores m\u00e1s citados del mundo. Thompson Reuters lo incluy\u00f3 en el listado Highly Cited Researchers 2014, que recoge los cient\u00edficos m\u00e1s citados de cada campo, teniendo en cuenta los art\u00edculos que se han situado entre el 1 por ciento m\u00e1s citados de cada a\u00f1o, entre 2002 y 2012. Se cuenta entre 3.200 investigadores de 21 campos cient\u00edficos, y \u00e9l es uno de los 114 m\u00e1s citados del \u00e1rea de Ciencias Agr\u00edcolas.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p> Josep Llu\u00eds Domingo es editor jefe de la revista \u00abFood and chemical toxicology\u00bb, desde el 1 de enero de 2015. Ya desde el a\u00f1o 2011, el catedr\u00e1tico de Toxicolog\u00eda era managing editor. El investigador es tambi\u00e9n editor jefe de la revista \u00abEnvironmental Research\u00bb<\/p>\n","protected":false},"author":12,"featured_media":6115,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[101,117,254,83,89,124,120],"tags":[1467,1471],"class_list":["post-6125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-centros-de-investigacion-urv","category-ciencia-y-tecnologia","category-facultat-medicina-ciencias-salud","category-general-es","category-pdi-es","category-portada-es","category-salud","tag-salud-medioambiental","tag-toxicologia-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/6125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/comments?post=6125"}],"version-history":[{"count":0,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/6125\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media\/6115"}],"wp:attachment":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media?parent=6125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/categories?post=6125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/tags?post=6125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}