{"id":12774,"date":"2015-10-06T16:20:41","date_gmt":"2015-10-06T14:20:41","guid":{"rendered":"http:\/\/ddurv.taller.fesomia.net\/?p=12774"},"modified":"2015-10-08T18:23:34","modified_gmt":"2015-10-08T16:23:34","slug":"proyecto-equality-seleccionado-europa-buena-practica-cambio-social","status":"publish","type":"post","link":"https:\/\/ddurv.taller.fesomia.net\/es\/proyecto-equality-seleccionado-europa-buena-practica-cambio-social\/","title":{"rendered":"El proyecto Equality, seleccionado en Europa como buena pr\u00e1ctica para el cambio social"},"content":{"rendered":"<p>La Comisi\u00f3n Europea (CE) ha seleccionado el proyecto Equality de entre los 51 financiados por el programa ALFA desde el a\u00f1o 2007 como ejemplo de buena pr\u00e1ctica de fortalecimiento institucional. As\u00ed lo especifica en el informe <em>Higher education cooperation between the European Union, Latin America and the Caribbean: Academic cooperation and mobility: bringing the two regions closer<\/em>, sobre el impacto de los programas de cooperaci\u00f3n acad\u00e9mica que la Uni\u00f3n Europea ha llevado a cabo en Am\u00e9rica Latina y el Caribe. La CE destaca del proyecto su contribuci\u00f3n al cambio social en el \u00e1mbito del g\u00e9nero.<\/p>\n<p>El proyecto Equality (Strengthening Women\u2019s Leadership in Latin American HEIs and Society) moderniz\u00f3 universidades de 18 pa\u00edses de Am\u00e9rica Latina y 4 de Europa para promover la igualdad de g\u00e9nero en la educaci\u00f3n y en el mercado de trabajo entre los a\u00f1os 2011 y 2014. La URV, a trav\u00e9s del Observatorio de la Igualdad, lider\u00f3 la implementaci\u00f3n de Planes de Igualdad en las universidades participantes de Equality.<\/p>\n<p>El proyecto, que finaliz\u00f3 en diciembre de 2014, tiene continuidad mediante la Red Equality, una plataforma para el intercambio de buenas pr\u00e1cticas en la gesti\u00f3n de la igualdad de g\u00e9nero en las instituciones de educaci\u00f3n superior. La red, de la que la URV ocupa la vicepresidencia, cuenta con 14 socios y est\u00e1 abierta a las universidades de cualquier pa\u00eds que quieran adherirse.<\/p>\n<h5>M\u00e1s informaci\u00f3n:<\/h5>\n<p><a href=\"http:\/\/bookshop.europa.eu\/en\/higher-education-cooperation-between-the-european-union-latin-america-and-the-caribbean-pbEC0115210\/\">Informe <em>Higher education cooperation between the European Union, Latin America and the Caribbean: Academic cooperation and mobility: bringing the two regions closer<\/em>, de la CE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Comisi\u00f3n Europea ha elegido el proyecto Equality como buena pr\u00e1ctica de cooperaci\u00f3n acad\u00e9mica en una publicaci\u00f3n que recoge el impacto de los programas que la UE ha llevado a cabo en Am\u00e9rica Latina y el Caribe. El Observatorio de la Igualdad de la URV particip\u00f3 en este proyecto, liderando la implementaci\u00f3n de los Planes de Igualdad en las universidades participantes<\/p>\n","protected":false},"author":12,"featured_media":12663,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[124,121],"tags":[2228,2515,2229],"class_list":["post-12774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portada-es","category-sociedad-y-cultura","tag-comision-europea","tag-observatorio-de-la-igualdad","tag-proyecto-equality"],"acf":[],"_links":{"self":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/12774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/comments?post=12774"}],"version-history":[{"count":0,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/12774\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media\/12663"}],"wp:attachment":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media?parent=12774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/categories?post=12774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/tags?post=12774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}