{"id":11240,"date":"2014-03-10T13:25:42","date_gmt":"2014-03-10T12:25:42","guid":{"rendered":"http:\/\/ddurv.taller.fesomia.net\/?p=11240"},"modified":"2015-07-24T13:30:36","modified_gmt":"2015-07-24T11:30:36","slug":"desarrollan-celulas-de-silicio-capaces-de-captar-la-radiacion-infrarroja","status":"publish","type":"post","link":"https:\/\/ddurv.taller.fesomia.net\/es\/desarrollan-celulas-de-silicio-capaces-de-captar-la-radiacion-infrarroja\/","title":{"rendered":"Desarrollan c\u00e9lulas de silicio capaces de captar la radiaci\u00f3n infrarroja"},"content":{"rendered":"<p>Un equipo de investigadores del Consejo Superior de Investigaciones Cient\u00edficas (CSIC), la Universitat Polit\u00e8cnica de Val\u00e8ncia, la Universitat Polit\u00e8cnica de Catalunya BarcelonaTech (UPC) y la Universitat Rovira i Virgili ha creado una c\u00e9lula fotovoltaica de silicio capaz de transformar en electricidad la radiaci\u00f3n infrarroja. El trabajo aparece publicado esta semana en la revista <em>Nature Communications<\/em>.<\/p>\n<p>El sol\u00a0es una fuente inagotable de energ\u00eda que, de ser muy explotada, podr\u00eda solucionar muchos de los problemas energ\u00e9ticos actuales. El dispositivo capaz de realizar la conversi\u00f3n de luz solar en electricidad es la c\u00e9lula fotovoltaica, com\u00fanmente conocida como c\u00e9lula solar. Pero existen varios obst\u00e1culos que impiden una mayor generalizaci\u00f3n de su uso, entre ellos un coste relativamente alto (de la orden de 20 c\u00e9ntimos de euro por vatio producido) y una eficiencia baja, por debajo del 17 por ciento. Esto quiere decir que de cada vatio que recibimos del solo, s\u00f3lo a aprovechamos una peque\u00f1a parte, los 0,17 vatios que corresponden al espectro visible.<\/p>\n<p>El motivo de la baja eficiencia de las c\u00e9lulas fotovoltaicas convencionales reside que los materiales b\u00e1sicos para su fabricaci\u00f3n, como el silicio, son baratos de producir, pero s\u00f3lo pueden absorber y aprovechar una peque\u00f1a parte del espectro solar. El resto de la radiaci\u00f3n solar, que corresponde en la zona infrarroja, no es aprovechada y se pierde.<\/p>\n<figure id=\"attachment_11235\" aria-labelledby=\"figcaption_attachment_11235\" class=\"wp-caption alignnone\" style=\"width: 700px\"><a href=\"http:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/07\/140310esquemacelulasilicio.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11235\" src=\"http:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/07\/140310esquemacelulasilicio.jpg\" alt=\"Esquema de funcionamiento de la c\u00e9lula.\" width=\"700\" height=\"719\" srcset=\"https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/07\/140310esquemacelulasilicio.jpg 700w, https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/07\/140310esquemacelulasilicio-292x300.jpg 292w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><figcaption id=\"figcaption_attachment_11235\" class=\"wp-caption-text\">Esquema de funcionamiento de la c\u00e9lula.<\/figcaption><\/figure>\n<p>El profesor de investigaci\u00f3n del CSIC que ha liderado el proyecto, Francisco Meseguer -que actualmente trabaja en el Centro de Tecnolog\u00edas F\u00edsicas de la UPV\/Unidad Asociada del Instituto de Ciencia de Materiales de Madrid-, explica que \u00abnuestro equipo de investigaci\u00f3n, despu\u00e9s de tres a\u00f1os de trabajo, ha desarrollado un nuevo concepto de c\u00e9lula solar de silicio capaz tambi\u00e9n de captar y transformar en electricidad la radiaci\u00f3n infrarroja del sol\u00bb.<\/p>\n<p>El investigador de la URV Llu\u00eds Marsal, responsable del grupo de investigaci\u00f3n Sistemas Nanoelectr\u00f2nics y Fot\u00f3nicos (NePhoS) del Departamento de Ingenier\u00eda Electr\u00f3nica y Autom\u00e1tica destaca que estas nuevas c\u00e9lulas solares \u00abson esferas de silicio de medida microm\u00e8trica (un micr\u00f3metro se la millon\u00e9sima parte de un metro) y donde la luz infrarroja queda atrapada a la microesfera hasta que es absorbida por el silicio y se convierte en electricidad\u00bb. Por su geometr\u00eda esf\u00e9rica, \u00abla variaci\u00f3n de la eficiencia de estas c\u00e9lulas solares respete el \u00e1ngulo de incidencia de la luz es muy menor, permitiendo una mayor captaci\u00f3n de la luz independientemente del \u00e1ngulo.<\/p>\n<p>Este trabajo supone un nuevo enfoque cient\u00edfico para poder desarrollar en el futuro c\u00e9lulas fotovoltaicas de alto rendimiento.<\/p>\n<div class=\"panel rel\">\n<p><a class=\"external\" href=\"http:\/\/dx.doi.org\/10.1038\/ncomms4440\" target=\"_blank\" rel=\"external\">Referencia: M. Gar\u00edn, R. Fenollosa, R. Alcubilla, L. Shi, L.F. Marsal y F. Meseguer: \u00abAll-silicon spherical-Mie-resonator photodiode with spectral response in the infrared region\u00bb<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los resultados de la investigaci\u00f3n, que podr\u00edan servir para crear c\u00e9lulas fotovoltaicas de alto rendimiento, se han publicado a la revista &#8216;Nature Communications&#8217;<\/p>\n","protected":false},"author":11,"featured_media":11238,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[101,117,102,100,124],"tags":[1997,406,1998,1992,988,1999,2000],"class_list":["post-11240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-centros-de-investigacion-urv","category-ciencia-y-tecnologia","category-comciencia-es","category-investigacion","category-portada-es","tag-celula-fotovoltaica","tag-csic-es","tag-departamento-de-ingenieria-electronica-y-automatica","tag-nature-communications","tag-nephos-es","tag-radiacion-infraroja","tag-silicio"],"acf":[],"_links":{"self":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/11240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/comments?post=11240"}],"version-history":[{"count":0,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/11240\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media\/11238"}],"wp:attachment":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media?parent=11240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/categories?post=11240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/tags?post=11240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}