{"id":10985,"date":"2014-04-09T10:32:26","date_gmt":"2014-04-09T08:32:26","guid":{"rendered":"http:\/\/ddurv.taller.fesomia.net\/?p=10985"},"modified":"2015-07-20T10:37:38","modified_gmt":"2015-07-20T08:37:38","slug":"el-instituto-vila-seca-y-berenguer-dentenca-de-lhospitalet-de-linfant-ganan-dos-categorias-del-concurso-de-cristalizacion-en-la-escuela","status":"publish","type":"post","link":"https:\/\/ddurv.taller.fesomia.net\/es\/el-instituto-vila-seca-y-berenguer-dentenca-de-lhospitalet-de-linfant-ganan-dos-categorias-del-concurso-de-cristalizacion-en-la-escuela\/","title":{"rendered":"El Instituto Vila-seca y Berenguer d&#8217;Enten\u00e7a de l&#8217;Hospitalet de l&#8217;Infant, ganan dos categor\u00edas del concurso de Cristalizaci\u00f3n en la Escuela"},"content":{"rendered":"<p>El viernes 4 de abril, el Pati\u00a0de Lletres\u00a0del Edificio Hist\u00f3rico de la UB acogi\u00f3 la jornada final del certamen y la entrega de premios a los ganadores, en una sesi\u00f3n que este a\u00f1o coincide con la celebraci\u00f3n del A\u00f1o Internacional de la Cristalograf\u00eda.<\/p>\n<p>Durante la jornada, los alumnos participantes mostraron los trabajos cristalogr\u00e1ficos que hab\u00edan llevado a cabo durante los meses de enero a marzo y presentaron, mediante p\u00f3steres cient\u00edficos, todo el proceso que hab\u00edan seguido para obtenerlos. Finalmente, el jurado determin\u00f3 los ganadores de las diferentes categor\u00edas (cristal \u00fanico, composici\u00f3n cristalina, mejor metodolog\u00eda de trabajo y presentaci\u00f3n, votaci\u00f3n popular y mejor filmaci\u00f3n). Los alumnos Aitor L\u00f3pez e Iv\u00e1n Gonz\u00e1lez -con Andreu Faro como profesor-, del Instituto de Vila-seca fueron los ganadores del primer premio en la categor\u00eda de cristal \u00fanico, mientras que el primer premio en la categor\u00eda de composici\u00f3n cristalina fue por los alumnos: Guillermo Lled\u00f3, Joan Fern\u00e1ndez y Paula L\u00f3pez del Instituto Berenguer de Enten\u00e7a de l&#8217;Hospitalet de l&#8217;Infant, con los profesores Llu\u00efsa Mas, Miquel Pellicer y Maria Dolors Dom\u00e8nech.<\/p>\n<figure id=\"attachment_10977\" aria-labelledby=\"figcaption_attachment_10977\" class=\"wp-caption alignnone\" style=\"width: 700px\"><a href=\"http:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/07\/cristalvilasecapremi.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10977 size-full\" src=\"http:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/07\/cristalvilasecapremi.jpg\" alt=\"\" width=\"700\" height=\"508\" srcset=\"https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/07\/cristalvilasecapremi.jpg 700w, https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/07\/cristalvilasecapremi-300x218.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><figcaption id=\"figcaption_attachment_10977\" class=\"wp-caption-text\">Ganadores del primer premio en la categor\u00eda de cristal \u00fanico.<\/figcaption><\/figure>\n<h5>Formaci\u00f3n para profesores y alumnos<\/h5>\n<p>El pasado diciembre los profesores de secundaria recibieron sesiones de formaci\u00f3n a la Facultad de Qu\u00edmica de la URV, en las que se los ofreci\u00f3 conceptos fundamentales de cristalograf\u00eda y cristalizaci\u00f3n que los permitieron explicar a sus alumnos los procedimientos que ten\u00edan que seguir para llevar a cabo las experiencias de cristalizaci\u00f3n y obtener los cristales para participar en el concurso.<\/p>\n<p>Despu\u00e9s de un tiempo de trabajo de los alumnos a los centros, ayudados por los profesores y asesorados por los miembros de los equipos de investigaci\u00f3n de las universidades -con visitas a algunos de ellos como fue el caso de los institutos de las comarcas tarraconenses-, los institutos seleccionaron los trabajos, y estos se presentaron en un acto en la Universitat de Barcelona que simul\u00f3 un congreso cient\u00edfico. Por eso, los alumnos no s\u00f3lo ten\u00edan que mostrar los cristales obtenidos sino que tambi\u00e9n tuvieron que preparar un p\u00f3ster cient\u00edfico para explicar el proceso que siguieron, el trabajo realizado y los resultados obtenidos. Los ganadores ir\u00e1n ahora a la final estatal, que se har\u00e1 en Madrid.<\/p>\n<figure id=\"attachment_10983\" aria-labelledby=\"figcaption_attachment_10983\" class=\"wp-caption alignnone\" style=\"width: 700px\"><a href=\"http:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/07\/cristalhospibo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10983\" src=\"http:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/07\/cristalhospibo.jpg\" alt=\"Ganadores del primer premio en la categoria de composici\u00f3n cristalina.\" width=\"700\" height=\"464\" srcset=\"https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/07\/cristalhospibo.jpg 700w, https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/07\/cristalhospibo-300x199.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><figcaption id=\"figcaption_attachment_10983\" class=\"wp-caption-text\">Ganadores del primer premio en la categor\u00eda de composici\u00f3n cristalina.<\/figcaption><\/figure>\n<p>El equipo organizador de la Universitat Rovira i Virgili ha sido formado por Magdalena Aguil\u00f3, Francesc D\u00edaz, Joan Josep Carvajal, Maria Cinta Pujol, Rosa Maria Sol\u00e9 y Laura Escorihuela del Grupo de F\u00edsica y Cristalograf\u00eda de los Materiales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cerca de 1.250 alumnos de 52 centros de todo Catalu\u00f1a han participado en el concurso<\/p>\n","protected":false},"author":11,"featured_media":10980,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[117,102,255,124,111],"tags":[1410,1935,1507],"class_list":["post-10985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-y-tecnologia","category-comciencia-es","category-facultad-de-quimica","category-portada-es","category-urv-secundaria-es","tag-cristalografia","tag-grupo-de-fisica-y-cristalografia-de-los-materiales","tag-premios"],"acf":[],"_links":{"self":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/10985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/comments?post=10985"}],"version-history":[{"count":0,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/10985\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media\/10980"}],"wp:attachment":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media?parent=10985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/categories?post=10985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/tags?post=10985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}