{"id":10855,"date":"2014-05-21T10:58:22","date_gmt":"2014-05-21T08:58:22","guid":{"rendered":"http:\/\/ddurv.taller.fesomia.net\/?p=10855"},"modified":"2015-07-17T11:11:23","modified_gmt":"2015-07-17T09:11:23","slug":"job-in-la-herramienta-que-predice-a-los-candidatos-mas-adecuados-para-un-puesto-de-trabajo","status":"publish","type":"post","link":"https:\/\/ddurv.taller.fesomia.net\/es\/job-in-la-herramienta-que-predice-a-los-candidatos-mas-adecuados-para-un-puesto-de-trabajo\/","title":{"rendered":"&#8216;Job In&#8217;: la herramienta que predice a los candidatos m\u00e1s adecuados para un puesto de trabajo"},"content":{"rendered":"<p>Una aplicaci\u00f3n web desarrollada en el Departamento de Psicolog\u00eda de la URV facilita los procesos de reclutamiento y preselecci\u00f3n de personal en empresas del sector hotelero y hostelero. Se trata de <em>Job In<\/em>, una herramienta que selecciona de forma autom\u00e1tica los mejores candidatos en base a una serie de preguntas relacionadas con las actitudes y habilidades necesarias para hacer un trabajo de calidad. Todo el proceso se realiza de forma <em>on-line<\/em>, lo que simplifica la tarea tanto de los candidatos como de las empresas. Seg\u00fan sus creadores, gracias a <em>Job In<\/em> el reclutamiento y preselecci\u00f3n de personal para puestos operativos del sector hotelero ser\u00e1 m\u00e1s fiable y m\u00e1s barato que con las herramientas actuales.<\/p>\n<p>Encontrar a la persona ideal para un puesto de trabajo no es f\u00e1cil, pero las herramientas adecuadas pueden simplificar mucho este proceso. <em>Job In<\/em> nace precisamente con este objetivo: utilizar m\u00e9todos y herramientas de evaluaci\u00f3n de la psicolog\u00eda, conjuntamente con procesos inform\u00e1ticos, para simplificar, mejorar y optimizar la selecci\u00f3n de personal en las empresas del sector de servicios. Es fruto de una investigaci\u00f3n del grupo METODOLO, del Centro de Investigaci\u00f3n en Evaluaci\u00f3n y Medida de la Conducta (CRAMC), liderada por el doctor Jordi Tous, del Departamento de Psicolog\u00eda de la URV. En el desarrollo inform\u00e1tico ha colaborado la empresa W3IS2, <em>spin-off<\/em> de la universidad.<\/p>\n<p><em>Job In<\/em> valora a los candidatos para los diversos perfiles profesionales y preselecciona aquellos que son m\u00e1s adecuados para cada puesto de trabajo. La aplicaci\u00f3n va m\u00e1s all\u00e1 del curr\u00edculo o la entrevista personal, y analiza las habilidades, las competencias personales y los perfiles de los puestos. \u00abNo hay ninguna herramienta en el mercado que tenga las funciones que tiene <em>Job In<\/em>\u00ab, explica Jordi Tous. \u00abMuchas de ellas facilitan la captaci\u00f3n de curr\u00edculos y la difusi\u00f3n de ofertas de plazas vacantes de las empresas a trav\u00e9s de la red, pero ninguna permite gestionar y elegir entre los candidatos, que es lo que ofrecemos nosotros\u00bb.<\/p>\n<h5>Preguntas relevantes en un cuestionario propio<\/h5>\n<p><em>Job In<\/em> parte de un cuestionario que el propio grupo ha dise\u00f1ado. Incorpora preguntas sobre el car\u00e1cter del candidato (responsabilidad, sinceridad&#8230;), sobre las competencias relacionadas con el puesto de trabajo (atenci\u00f3n al cliente, trabajo en equipo, resoluci\u00f3n de problemas&#8230;) y sobre rasgos demogr\u00e1ficos y motivacionales (motivaci\u00f3n en trabajos anteriores, experiencia&#8230;). Tambi\u00e9n incorpora preguntas filtro, para determinar la sinceridad del candidato en sus respuestas.<\/p>\n<p>La aplicaci\u00f3n se basa en las t\u00e9cnicas de la entrevista conductual y en el m\u00e9todo de incidentes cr\u00edticos. Esto quiere decir que la encuesta \u00absigue un guion pautado, buscando en los candidatos indicios de conductas similares a las que desarrollan los trabajadores expertos\u00bb, explica el doctor Tous. El grupo ha tomado como referencia diferentes encuestas, entrevistas previas y test aplicados a muestras de trabajadores del sector, y ha extra\u00eddo las preguntas m\u00e1s relevantes, es decir, \u00abaquellas donde la respuesta diferencia a los trabajadores m\u00e1s adecuados para ocupar cada lugar\u00bb.<\/p>\n<p>La experiencia de 12 a\u00f1os del grupo en este campo les ha permitido utilizar la informaci\u00f3n recogida en trabajos anteriores para validar la herramienta. Para ello, han utilizado una amplia muestra de personas que han trabajado en el sector hotelero, se han formado para trabajar en \u00e9l o han buscado trabajo en \u00e9l en los \u00faltimos a\u00f1os. \u00abLos resultados obtenidos no s\u00f3lo demuestran que tenemos una herramienta fiable y v\u00e1lida\u00bb, explica Jordi Tous, \u00absino que es la herramienta m\u00e1s adaptada al sector que podemos encontrar en la actualidad\u00bb.<\/p>\n<figure id=\"attachment_10844\" aria-labelledby=\"figcaption_attachment_10844\" class=\"wp-caption alignnone\" style=\"width: 700px\"><a href=\"http:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/07\/dsc0328.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10844\" src=\"http:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/07\/dsc0328.jpg\" alt=\"Jordi Tous, investigador de la URV, durante la presentaci\u00f3n de la aplicaci\u00f3n en Reus el pasado 15 de mayo.\" width=\"700\" height=\"457\" srcset=\"https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/07\/dsc0328.jpg 700w, https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/07\/dsc0328-300x196.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><figcaption id=\"figcaption_attachment_10844\" class=\"wp-caption-text\">Jordi Tous, investigador de la URV, durante la presentaci\u00f3n de la aplicaci\u00f3n en Reus el pasado 15 de mayo.<\/figcaption><\/figure>\n<h5>Una necesidad de las empresas hoteleras<\/h5>\n<p>Uno de los principales problemas que tienen las empresas hoteleras y hosteleras es la dificultad para encontrar los trabajadores adecuados, lo que conlleva una alta rotaci\u00f3n del personal. \u00abEsto sucede, en parte, porque el nivel del puesto de trabajo se considera bajo y los sueldos son discretos\u00bb, explica Tous. \u00abPodemos contribuir significativamente a mejorar la b\u00fasqueda y preselecci\u00f3n de candidatos en las empresas del sector servicios, mejorando la calidad del proceso y abaratando los costes\u00bb, concluye.<\/p>\n<p>La herramienta se present\u00f3 en Reus el pasado 15 de mayo, en el marco de unas jornadas organizadas por el Parque Cient\u00edfico y Tecnol\u00f3gico (PCT) de Turismo y Ocio y Activa M\u00fatua 2008, donde tuvo \u00abmuy buena acogida\u00bb, opina Tous. Ahora, el grupo se encuentra en la \u00faltima etapa del proceso, que es la de difundir y comercializar <em>Job In<\/em>. En este sentido, su trabajo empieza a dar frutos: la Escuela de Hosteler\u00eda de Cambrils ya la ha implementado; y recientemente se ha cerrado un acuerdo con la organizaci\u00f3n de los Juegos del Mediterr\u00e1neo 2017, por el cual se utilizar\u00e1 una adaptaci\u00f3n de <em>Job In<\/em> para hacer la clasificaci\u00f3n de los voluntarios. La herramienta est\u00e1 pensada para el sector hotelero y hostelero, pero tambi\u00e9n se puede utilizar en otros tipos de empresas de servicios o administraciones p\u00fablicas, ya que se pueden adecuar las competencias a perfiles diferentes. Pr\u00f3ximamente se presentar\u00e1 en otros lugares de la costa catalana, valenciana y andaluza.<\/p>\n<h5>El problema de la selecci\u00f3n a partir de curr\u00edculos<\/h5>\n<p>La selecci\u00f3n de personal se ha basado tradicionalmente en la recepci\u00f3n de curr\u00edculos y la elecci\u00f3n de aquellos m\u00e1s apropiados en funci\u00f3n de criterios como la experiencia en puestos similares, la buena impresi\u00f3n o la motivaci\u00f3n demostrada en una entrevista personal. Este es un sistema sesgado, que no tiene en cuenta aspectos directamente relacionados con el puesto de trabajo, como la capacidad de trabajo en equipo o la orientaci\u00f3n al cliente. Adem\u00e1s, la cantidad de curr\u00edculos recibida supera habitualmente la demanda real de puestos de trabajo, cosa que implica tener que leer y clasificar mucha informaci\u00f3n. Trabajar con este sistema supone una gran dedicaci\u00f3n de tiempo, y la acumulaci\u00f3n de curr\u00edculos de candidatos que no se ajustan a ninguno de los perfiles del sector.<\/p>\n<p>El grupo de Jordi Tous identific\u00f3 cuatro factores clave para agilizar los procesos de recursos humanos: la captaci\u00f3n y reclutamiento, el ajuste de los candidatos a los perfiles, la gesti\u00f3n f\u00e1cil y r\u00e1pida de la informaci\u00f3n, y la mejora continua de la calidad del producto final. La herramienta <em>Job In<\/em> es la culminaci\u00f3n de diferentes investigaciones en estos \u00e1mbitos; posteriormente, esta herramienta se codific\u00f3 inform\u00e1ticamente, hasta obtener el resultado final en forma de aplicaci\u00f3n web. \u00abEsta es una necesidad que ten\u00edamos detectada en las empresas, y la herramienta que hemos desarrollado les puede ser de gran valor\u00bb, explica Tous. \u00abEl coste inicial y los problemas derivados de su uso son muy reducidos, y en un par de a\u00f1os podr\u00edamos encontrarla en muchas m\u00e1s empresas\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La aplicaci\u00f3n la ha desarrollado el grupo de investigaci\u00f3n METODOLO, del Departamento de Psicolog\u00eda de la URV, y est\u00e1 orientada a las empresas del sector hotelero y hostelero<\/p>\n","protected":false},"author":11,"featured_media":10852,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[102,118,100,124,121],"tags":[1906,1262,1259,1907,1908,1909,624,629],"class_list":["post-10855","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comciencia-es","category-economia-y-empresa","category-investigacion","category-portada-es","category-sociedad-y-cultura","tag-curriculo","tag-metodolo","tag-psicologia","tag-servicios","tag-trabajo","tag-turismo","tag-w3is2","tag-w3is2-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/10855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/comments?post=10855"}],"version-history":[{"count":0,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/10855\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media\/10852"}],"wp:attachment":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media?parent=10855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/categories?post=10855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/tags?post=10855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}