{"id":10730,"date":"2014-05-27T13:52:15","date_gmt":"2014-05-27T11:52:15","guid":{"rendered":"http:\/\/ddurv.taller.fesomia.net\/?p=10730"},"modified":"2015-07-17T10:37:10","modified_gmt":"2015-07-17T08:37:10","slug":"cuatro-investigadores-de-la-urv-reconocidos-en-el-programa-icrea-academia-2013","status":"publish","type":"post","link":"https:\/\/ddurv.taller.fesomia.net\/es\/cuatro-investigadores-de-la-urv-reconocidos-en-el-programa-icrea-academia-2013\/","title":{"rendered":"Cuatro investigadores de la URV, reconocidos en el Programa ICREA Acad\u00e8mia 2013"},"content":{"rendered":"<p>Joan Maria Thom\u00e0s (Departamento de Historia e Historia del Arte), Jordi Mir\u00f3 (Departamento de Psicolog\u00eda), Josep Domingo-Ferrer (Departamento de Ingenier\u00eda Inform\u00e1tica y Matem\u00e1ticas) y Benjam\u00ed I\u00f1\u00edguez (Departamento de Ingenier\u00eda Electr\u00f3nica, El\u00e9ctrica y Autom\u00e1tica), han sido reconocidos por la Instituci\u00f3n Catalana de Investigaci\u00f3n y Estudios Avanzados (ICREA), en el programa ICREA Acad\u00e8mia 2013. Los dos \u00faltimos ya hab\u00edan sido distinguidos con este mismo reconocimiento en 2008.<\/p>\n<p>El Programa ICREA Acad\u00e8mia tiene la finalidad de incentivar y recompensar la excelencia investigadora del personal docente e investigador (PDI) doctor con vinculaci\u00f3n permanente en las universidades p\u00fablicas. Es un programa de intensificaci\u00f3n de la investigaci\u00f3n del profesorado que imparte docencia y que se encuentra en fase activa y de expansi\u00f3n de su actividad investigadora. De esta manera, se pretende que se puedan dedicar a su investigaci\u00f3n y a la retenci\u00f3n de talento investigador dentro del sistema universitario de Catalu\u00f1a.<\/p>\n<p>Durante cinco a\u00f1os, los investigadores reconocidos como ICREA Acad\u00e8mia reciben 16.000 euros brutos anuales y las universidades del investigador seleccionado, un canon de 4.000 euros anuales para la gesti\u00f3n del programa y 20.000 euros anuales m\u00e1s, que se destinan a financiar preferentemente la contrataci\u00f3n de personal para rebajar la tarea docente del premiado o ayudarle en acciones relacionadas con su actividad de investigaci\u00f3n. Los cuatro galardonados de la URV en la edici\u00f3n 2013 -del total de 29 que han sido reconocidos- han sido los doctores Joan Maria Thom\u00e0s, Jordi Mir\u00f3, Josep Domingo-Ferrer y Benjam\u00ed I\u00f1\u00edguez. Se da la circunstancia de que los dos \u00faltimos ya hab\u00edan recibido esta distinci\u00f3n en 2008.<\/p>\n<ul>\n<li class=\"first\"><strong>Joan Maria Thom\u00e0s<\/strong>. Es licenciado (UB) y doctorado (UAB) en Historia Contempor\u00e1nea. Ha sido investigador visitante y profesor en universidades de todo el mundo. Ha sido galardonado con el Premio Ciudad de Barcelona de Historia y el Premio de la Cr\u00edtica \u00abSerra d&#8217;Or\u00bb. Trabaja como profesor titular en la URV, donde coordina el Master de Sociedades Hist\u00f3ricas y Formas Pol\u00edticas en Europa y un proyecto de investigaci\u00f3n titulado \u00abEstados Unidos, Alemania, Reino Unido, Jap\u00f3n y sus relaciones con Espa\u00f1a durante la Segunda Guerra Mundial y la Primera Posguerra (1939-1953): nuevas perspectivas\u00bb. Ha escrito diez libros como \u00fanico autor -dos de ellos traducidos al ingl\u00e9s-, catorce como coautor, y diecinueve art\u00edculos. Lleva a cabo su investigaci\u00f3n a trav\u00e9s del Grupo Consolidado ISOCAC, es miembro de los consejos editoriales de varias publicaciones y pertenece a asociaciones hist\u00f3ricas de todo el mundo. Sus principales l\u00edneas de investigaci\u00f3n son el fascismo, el franquismo, la Guerra Civil, las relaciones de EEUU con Espa\u00f1a durante Guerra Civil espa\u00f1ola, la Segunda Guerra Mundial y la primera posguerra.<\/li>\n<li><strong>Jordi Mir\u00f3<\/strong>. Obtuvo la licenciatura en Psicolog\u00eda en la Universidad de Barcelona y el m\u00e1ster y doctorado en Psicolog\u00eda de la Salud de la UAB. Su formaci\u00f3n incluye puestos de profesor visitante en el Instituto de Evaluaci\u00f3n y Tratamiento del Dolor (Universidad de Pittsburgh) y el Centro de Dolor Multidisciplinar (Universidad de Washington) y una residencia rotatoria postdoctoral en la Universidad de Nueva York. Actualmente es catedr\u00e1tico de Psicolog\u00eda de la Salud y director de la Unidad para el Estudio y Tratamiento del Dolor &#8211; ALGOS de la URV. Es director del M\u00e1ster en Psicolog\u00eda de la Salud de la URV, universidad donde, en 2012, recibi\u00f3 el Reconocimiento a la Calidad de la Investigaci\u00f3n. Ha sido miembro fundador de la Sociedad Espa\u00f1ola del Dolor y es miembro activo de sociedades y foros internacionales relacionados con el dolor. Su inter\u00e9s en la investigaci\u00f3n se centra en el dolor y su tratamiento, pero su principal \u00e1rea de investigaci\u00f3n actual es el dolor pedi\u00e1trico y, especialmente, el dolor cr\u00f3nico en pediatr\u00eda. Su grupo (ALGOS) desarrolla diferentes aplicaciones de tel\u00e9fonos inteligentes para ayudar a las personas con dolor a desarrollar maneras m\u00e1s eficaces de tratar los problemas de salud.<\/li>\n<li><strong>Josep Domingo-Ferrer<\/strong>. Es Catedr\u00e1tico de Ciencia de la Computaci\u00f3n en la URV, donde dirige la C\u00e1tedra UNESCO de Privacidad de Datos. Obtuvo la licenciatura y el doctorado en inform\u00e1tica en la UAB. Tambi\u00e9n es licenciado en matem\u00e1ticas. Ha recibido el Premio de Investigaci\u00f3n Google (2014), el Premio ICREA Acad\u00e8mia (2008 y 2013) y la Medalla Narc\u00eds Monturiol (2012). Es miembro electo de la Acad\u00e8mia Europea (2012) del Instituto Internacional de Estad\u00edstica (2012), y miembro del Instituto de Ingenier\u00eda El\u00e9ctrica y Electr\u00f3nica (2011). Es autor de 5 patentes y m\u00e1s de 320 publicaciones. Ha sido el coordinador del proyecto europeo CO-ORTHOGONAL (del 5\u00ba Programa Marco) y de diferentes proyectos espa\u00f1oles y norteamericanos. Actualmente coordina el equipo CONSOLIDER \u00abARES\u00bb sobre seguridad y privacidad de datos. Sus intereses de investigaci\u00f3n son la privacidad y la seguridad de datos, concretamente la creaci\u00f3n de tecnolog\u00edas para conciliar la seguridad, la privacidad y la funcionalidad en la sociedad de la informaci\u00f3n.<\/li>\n<li class=\"last\"><strong>Benjam\u00ed I\u00f1iguez<\/strong>. Obtuvo el doctorado en F\u00edsica por la Universitat de les Illes Balears y ha trabajado como investigador postdoctoral en el Instituto Polit\u00e9cnico de Rensselaer (Troy, Nueva York), y en la Universidad Cat\u00f3lica de Lovaina (Louvain- la-Neuve, B\u00e9lgica), donde fue titular de una beca Marie Curie durante 24 meses. En 2001 se incorpor\u00f3 como profesor titular del Departamento de Electr\u00f3nica, El\u00e9ctrica y Autom\u00e1tica de la URV, donde fue ascendido a catedr\u00e1tico, en 2010. En 2004 obtuvo la Distinci\u00f3n de la Generalitat de Catalunya para la Promoci\u00f3n de la Investigaci\u00f3n Universitaria, en la categor\u00eda de J\u00f3venes Investigadores. Recibi\u00f3 el Premio ICREA Acad\u00e8mia 2008. Ha coordinado el proyecto \u00abComon\u00bb (Compact Modeling Network) financiado por la Uni\u00f3n Europea, en el 7\u00ba Programa Marco y ha participado, como l\u00edder del equipo, en cuatro proyectos del 6\u00ba y del 7\u00ba Programa Marco europeo. I\u00f1iguez ha publicado m\u00e1s de 100 art\u00edculos en revistas internacionales. Su principal inter\u00e9s de investigaci\u00f3n es el desarrollo de modelos orientados al dise\u00f1o compacto de los dispositivos semiconductores avanzados.<\/li>\n<\/ul>\n<p>La edici\u00f3n de 2013 ha sido la sexta de estos premios Acad\u00e8mia ICREA, impulsada por la Generalitat de Catalunya. Actualmente y con los cuatro nombrados en esta edici\u00f3n, ya han sido galardonados doce profesores de la URV: dos en 2008, Josep Domingo y Benjam\u00ed I\u00f1\u00edguez (que este a\u00f1o han vuelto a ser distinguidos); dos en 2009, Francesc Medina y Montserrat Di\u00e9guez; tres en 2010, Francesc D\u00edaz, \u00d2scar P\u00e0mies y Anthony Pym; uno en 2011, \u00c0lex Arenas; y dos en 2012, Eduard Llobet y Marta Sales-Pardo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El reconocimiento tiene el objetivo de incentivar y recompensar la excelencia investigadora del personal docente e investigador en las universidades p\u00fablicas catalanas<\/p>\n","protected":false},"author":11,"featured_media":10728,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[101,117,102,100,89,124,120,121],"tags":[389,1548,634,402],"class_list":["post-10730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-centros-de-investigacion-urv","category-ciencia-y-tecnologia","category-comciencia-es","category-investigacion","category-pdi-es","category-portada-es","category-salud","category-sociedad-y-cultura","tag-algos","tag-excelencia","tag-jordi-miro","tag-josep-domingo-ferrer"],"acf":[],"_links":{"self":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/10730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/comments?post=10730"}],"version-history":[{"count":0,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/10730\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media\/10728"}],"wp:attachment":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media?parent=10730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/categories?post=10730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/tags?post=10730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}