{"id":10570,"date":"2015-07-07T12:57:35","date_gmt":"2015-07-07T10:57:35","guid":{"rendered":"http:\/\/ddurv.taller.fesomia.net\/?p=10570"},"modified":"2015-07-29T13:02:50","modified_gmt":"2015-07-29T11:02:50","slug":"la-urv-encabeza-el-ranking-de-excelencia-con-liderazgo-cientifico-de-la-fundacion-cyd","status":"publish","type":"post","link":"https:\/\/ddurv.taller.fesomia.net\/es\/la-urv-encabeza-el-ranking-de-excelencia-con-liderazgo-cientifico-de-la-fundacion-cyd\/","title":{"rendered":"La URV encabeza el ranking de excelencia con liderazgo cient\u00edfico de la Fundaci\u00f3n CyD"},"content":{"rendered":"<p><span class=\"notranslate\">La Fundaci\u00f3n Conocimiento y Desarrollo (CYD) ha presentado este lunes el informe anual sobre la contribuci\u00f3n de las universidades al desarrollo, en el que dedica un cap\u00edtulo a analizar la producci\u00f3n cient\u00edfica de las universidades espa\u00f1olas y las instituciones de investigaci\u00f3n, a partir de indicadores que posicionan las universidades teniendo en cuenta los trabajos cient\u00edficos publicados durante el periodo 2009-2013.<\/span> <span class=\"notranslate\">Con los datos extra\u00eddos del\u00a0<em>SCImago Institutions Rankings<\/em> (SIR) elaborado en base los datos de Scopus de este periodo, se analizan cuatro indicadores: la producci\u00f3n cient\u00edfica -la cantidad de art\u00edculos cient\u00edficos publicados-, el impacto normalizado -que mide la relaci\u00f3n entre el impacto cient\u00edfico medio de una instituci\u00f3n y la media mundial-, el porcentaje de las publicaciones que se encuentran en el primer cuartil -indica que las revistas corresponden al grupo del 25% de publicaciones con un factor de impacto m\u00e1s alto &#8211; y, finalmente, el liderazgo con excelencia -el porcentaje de trabajos publicados entre el 10% de los m\u00e1s citados en los que la instituci\u00f3n ha liderado la investigaci\u00f3n.<\/span><\/p>\n<p><span class=\"notranslate\">En este indicador es, precisamente, donde la URV sale mejor posicionada.<\/span> <span class=\"notranslate\">De hecho, en excelencia con liderazgo destaca en el ranking general como la primera del Estado de las 59 que aparecen, con una tasa del 11,52%, superior al 10% que es la media mundial.<\/span> <span class=\"notranslate\">Este indicador muestra no s\u00f3lo la alta visibilidad de la producci\u00f3n cient\u00edfica, sino la capacidad e iniciativa de los investigadores de la instituci\u00f3n ya que se trata del n\u00famero de documentos incluidos en la ratio de excelencia liderados por investigadores de la Universidad.<\/span><\/p>\n<p><span class=\"notranslate\">En este indicador la URV se encuentra en primera posici\u00f3n en cuatro de las seis \u00e1reas analizadas: Ingenier\u00eda (17,32), F\u00edsica y Astronom\u00eda (11,20), Ciencia Agr\u00edcola y Biol\u00f3gica (11,81) y Ciencias de la Computaci\u00f3n (13 , 20).<\/span> <span class=\"notranslate\">En las altas dos \u00e1reas restantes, Medicina y Bioqu\u00edmica, Gen\u00e9tica y Biolog\u00eda Molecular se sit\u00faa en tercera posici\u00f3n del Estado (6,65 y 7,06 respectivamente).<\/span><\/p>\n<p><span class=\"notranslate\">En cuanto al \u00edndice de impacto normalizado, las citas que reciben los art\u00edculos cient\u00edficos, la UPF (1,68) y la UB (1,56) encabezan el ranking y la tercera universidad es la UAB (1,50) que supera por una d\u00e9cima a la URV (1,49).<\/span> <span class=\"notranslate\">En este indicador a\u00fan as\u00ed, la Universidad destaca en las \u00e1reas de Ingenier\u00eda (en primera posici\u00f3n con un 2,87) Ciencia Agr\u00edcola y Biol\u00f3gica (en segunda posici\u00f3n con un 1,69) y en Bioqu\u00edmica, Gen\u00e9tica y Biolog\u00eda Molecular, ( en tercera posici\u00f3n con un 1,35).<\/span><\/p>\n<p><span class=\"notranslate\">El conjunto de indicadores analizados en el apartado de producci\u00f3n cient\u00edfica posicionan la URV entre las tres universidades espa\u00f1olas que se encuentran en las lugares m\u00e1s destacados en un n\u00famero m\u00e1s alto de indicadores.<\/span> <span class=\"notranslate\">La Universidad es, de hecho, la que se encuentra en m\u00e1s ocasiones entre las tres primeras posiciones (12 veces teniendo en cuenta todos los indicadores), seguida de la UB y la UPF.<\/span><\/p>\n<p><span class=\"notranslate\">El informe se puede descargar <a href=\"https:\/\/translate.googleusercontent.com\/translate_c?act=url&amp;depth=1&amp;hl=es&amp;ie=UTF8&amp;prev=_t&amp;rurl=translate.google.com&amp;sl=ca&amp;tl=es&amp;u=http:\/\/linkis.com\/www.fundacioncyd.org\/EqVy4&amp;usg=ALkJrhgHWsbwVCB2D4dRo11gMNcwFtnLHA\">aqu\u00ed<\/a> (los datos de producci\u00f3n cient\u00edfica se encuentran en el cap\u00edtulo 5: Indicadores de producci\u00f3n cient\u00edfica de las universidades espa\u00f1olas y las instituciones de investigaci\u00f3n).<\/span> <span class=\"notranslate\">Este trabajo analiza tambi\u00e9n la oferta y la demanda universitaria y la investigaci\u00f3n, la cultura emprendedora y la empresa.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La URV ha vuelto a posicionarse en primera posici\u00f3n del Estado en excelencia con liderazgo cient\u00edfico, seg\u00fan el informe de la Fundaci\u00f3n Conocimiento y Desarrollo que analiza la situaci\u00f3n de la universidad espa\u00f1ola y su contribuci\u00f3n al desarrollo econ\u00f3mico y social . Encabeza este indicador a nivel general y tambi\u00e9n en las \u00e1reas de Ingenier\u00eda, F\u00edsica y Astronom\u00eda, Ciencia Agr\u00edcola y Biolog\u00eda y Ciencias de la Computaci\u00f3n<\/p>\n","protected":false},"author":11,"featured_media":10568,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[125,97,102,83,94,100,124],"tags":[1871,415,404],"class_list":["post-10570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-banner-es","category-calidad-urv","category-comciencia-es","category-general-es","category-institucion","category-investigacion","category-portada-es","tag-fundacion-cyd","tag-ranking","tag-ranquing-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/10570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/comments?post=10570"}],"version-history":[{"count":0,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/10570\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media\/10568"}],"wp:attachment":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media?parent=10570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/categories?post=10570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/tags?post=10570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}