{"id":10330,"date":"2015-06-30T11:00:46","date_gmt":"2015-06-30T09:00:46","guid":{"rendered":"http:\/\/ddurv.taller.fesomia.net\/european-university-association-eua-debat-sobre-el-futur-dels-estudis-de-doctorat-2\/"},"modified":"2015-07-01T08:40:19","modified_gmt":"2015-07-01T06:40:19","slug":"european-university-association-eua-debat-sobre-el-futur-dels-estudis-de-doctorat","status":"publish","type":"post","link":"https:\/\/ddurv.taller.fesomia.net\/es\/european-university-association-eua-debat-sobre-el-futur-dels-estudis-de-doctorat\/","title":{"rendered":"European University Association (EUA) debate sobre el futuro de los estudios de doctorado"},"content":{"rendered":"<p>\u00c9sta es la reuni\u00f3n internacional m\u00e1s amplia que se convoca sobre la formaci\u00f3n doctoral. En los \u00faltimos 15 a\u00f1os, las universidades han alineado los estudios de doctorado que imparten com sus estrategias de investigaci\u00f3n, y han creado estructuras para la gesti\u00f3n profesional de esta etapa de postgrado. Se ha superado, pues, la etapa en que el doctoradp se limitaba a una simple relaci\u00f3n persona supervisora-supervisada, y en la actualidad es una actividad acad\u00e9mica en la que la instituci\u00f3n que la acoge tiene mucho m\u00e1s que decir.<\/p>\n<p>En el Council for Doctoral Education (CDE) se ha analizado c\u00f3mo influyen los nuevos retos a los que se enfrentan las universidades, en los estudios de doctorado. Los retos son la digitalizaci\u00f3n, los MOOCs, los dilemas \u00e9ticos, la financiaci\u00f3n competitiva basada en una buena gesti\u00f3n y la necesidad de demostrar el impacto de las investigaciones. La investigaci\u00f3n y la formaci\u00f3n doctoral tienen cada vez m\u00e1s importancia. Com deben prepararse, pues, los futuros doctores?<\/p>\n<p><a href=\"http:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/doctorateuamunich1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-10294 size-large\" src=\"http:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/doctorateuamunich1-1024x775.jpg\" alt=\"doctorateuamunich\" width=\"1024\" height=\"775\" srcset=\"https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/doctorateuamunich1-1024x775.jpg 1024w, https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/doctorateuamunich1-300x227.jpg 300w, https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/doctorateuamunich1-768x581.jpg 768w, https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/doctorateuamunich1-1536x1162.jpg 1536w, https:\/\/ddurv.taller.fesomia.net\/wp-content\/uploads\/2015\/06\/doctorateuamunich1-2048x1549.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>La reuni\u00f3n se ha estructurado en cinco sesiones plenarias: Los retos de las universidades; El libre acceso, la investigaci\u00f3n \u00e9tica y la capacidad de construir. Tres estudios de caso; La formaci\u00f3n doctoral colaborativa; EUA-CDE 2014-15; y Los avances de Salzburg: la gesti\u00f3n profesional, las habilidades a adquirir y una mejor supervisi\u00f3n del doctorado.<\/p>\n<p>El objetivo del Consejo ha sido el debate entre los diferentes actores del proceso de formaci\u00f3n doctoral: dirigentes universitarios, investigadores, responsables pol\u00edticos, organismos de financiaci\u00f3n y agencias de calidad, entre otros.<\/p>\n<p>Las discusiones de la reuni\u00f3n de este a\u00f1o se incorporar\u00e1n a la nueva iniciativa pol\u00edtica de la EUA-CDE, relativa a la formaci\u00f3n doctoral, que lleva por t\u00edtulo: <a href=\"http:\/\/www.eua.be\/cde\/the-shape-things-to-come.aspx\">The Shape of Things to Come<\/a><\/p>\n<p>El pr\u00f3ximo 2016 la reuni\u00f3n anual de CDE tendr\u00e1 lugar en Tarragona, tras haber sido escogida la candidatura de la URV entre las presentadas. El CDE naci\u00f3 en el a\u00f1o 2008, y desde entonces las reuniones se han celebrado en diferentes capitales y ciudades europeas: en Liverpool (2014), Varsovia (2013), Estocolmo (2012), Madrid (2011), Berl\u00edn (2010), Lausana (2009), y este a\u00f1o Munich.<\/p>\n<p><strong>Mas informaci\u00f3n: <\/strong><\/p>\n<p><a href=\"http:\/\/www.eua.be\/eua-cde-munich.aspx\">http:\/\/www.eua.be\/eua-cde-munich.aspx<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Consejo de Formaci\u00f3n Doctoral (CDE) de la EUA ha reunido 240 participantes de 34 pa\u00edses, en su 8\u00aa reuni\u00f3n anual para debatir la situaci\u00f3 actual y el futuro de los estudios de doctorado. Se ha celebrado los d\u00edas 18 y 19 de junio en la Universidad T\u00e9cnica de Munich, y la URV ha estado presente. Tarragona ser\u00e1 la sede de la pr\u00f3xima edici\u00f3n de la reuni\u00f3n anual del CDE, los d\u00edas 16 y 17 de junio de 2016<\/p>\n","protected":false},"author":12,"featured_media":10287,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[91,241,94,100,124],"tags":[524],"class_list":["post-10330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-docencia","category-escuela-de-postgrado-y-doctorado","category-institucion","category-investigacion","category-portada-es","tag-doctorado"],"acf":[],"_links":{"self":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/10330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/comments?post=10330"}],"version-history":[{"count":0,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/10330\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media\/10287"}],"wp:attachment":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media?parent=10330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/categories?post=10330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/tags?post=10330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}