{"id":10075,"date":"2015-06-23T15:45:18","date_gmt":"2015-06-23T13:45:18","guid":{"rendered":"http:\/\/ddurv.taller.fesomia.net\/signat-el-contracte-per-a-la-construccio-dun-pavello-esportiu-i-una-residencia-universitaria-al-complex-sant-jordi-de-tarragona-2\/"},"modified":"2015-07-01T10:01:16","modified_gmt":"2015-07-01T08:01:16","slug":"signat-el-contracte-per-a-la-construccio-dun-pavello-esportiu-i-una-residencia-universitaria-al-complex-sant-jordi-de-tarragona","status":"publish","type":"post","link":"https:\/\/ddurv.taller.fesomia.net\/es\/signat-el-contracte-per-a-la-construccio-dun-pavello-esportiu-i-una-residencia-universitaria-al-complex-sant-jordi-de-tarragona\/","title":{"rendered":"Firmado el contrato para construir un pabell\u00f3n deportivo y una residencia universitaria en el Complejo San Jordi"},"content":{"rendered":"<p>Han firmado el contrato Josep Anton Ferr\u00e9, rector de la URV, y Jaime Gross, director general Viding Fitness SLU, en presencia de Josep F\u00e8lix Ballesteros, alcalde de Tarragona; Joaquim Nin, delegado del Gobierno de la Generalitat en Tarragona; M\u00f2nica Garay, directora delegada de RESA (Residencias Universitarias), y Xavier Farriol, delegado del rector de Organizaci\u00f3n y Recursos de la URV.<\/p>\n<p>Se construir\u00e1 una nueva residencia universitaria junto a la existente y un nuevo pabell\u00f3n deportivo en el complejo Sant Jordi de Tarragona, en pleno casco urbano, que estar\u00e1n terminados en 2017. La instalaci\u00f3n deportiva se utilizar\u00e1 para los Juegos del Mediterr\u00e1neo 2017, para las competiciones de voleibol, y una vez terminados los Juegos se reconvertir\u00e1 en un complejo deportivo al servicio de los universitarios y del p\u00fablico en general. La inversi\u00f3n total prevista es de 12 millones de euros, y Viding y RESA tendr\u00e1n un periodo de explotaci\u00f3n de los dos equipamientos por 40 a\u00f1os.<\/p>\n<p>Tras la firma del contrato, Xavier Farriol manifest\u00f3 que este es un proyecto complejo, que ha exigido un trabajo intenso y coordinado entre todas las partes para que pueda materializarse en el tiempo previsto. Agradeci\u00f3 a diferentes servicios de la Universidad el trabajo realizado. La ubicaci\u00f3n es en el solar de forma irregular con fachada a la Avda. Llu\u00eds Companys, Marqu\u00e9s Gaud el Jel\u00fa y Avda. de Andorra de la ciudad, donde estaba el Complejo San Jordi y est\u00e1 actualmente la residencia San Jordi que gestiona RESA. Se prev\u00e9 poder tener la licencia de obras para septiembre y empezar a construir. Una plaza y un aparcamiento unir\u00e1n los diferentes espacios, dando coherencia al conjunto. El proyecto de la residencia es de CMT Arquitectes Associats SLP\u00a0<span style=\"font-family: Calibri;\"> (<\/span>Joan FC. Chico), y el del equipamiento deportivo y el espacio de relaci\u00f3n es de Josep Ferrando Architects.<\/p>\n<p>M\u00f2nica Garay (RESA) ha explicado que la nueva residencia ofrecer\u00e1 80 estudios con cocina para una o dos personas, m\u00e1ximo 160. Esta capacidad (en m\u00e1s de 3.000 m2 de superficie) se a\u00f1adir\u00e1 a la de la residencia actual, que es de 170 personas. El reto, dijo, es crear un espacio \u00fanico, integrando el actual y el futuro, para dar servicio a los diferentes p\u00fablicos de la Universidad: estudiantes de grado, de m\u00e1ster, profesorado e investigadores, ya la vitalidad que muestra la URV.<\/p>\n<p>Jaime Gross es director general de Viding Fitness SLU, empresa especializada en la construcci\u00f3n y gesti\u00f3n de centros deportivos. Para \u00e9l el proyecto de Tarragona es un \u00abproyecto ilusionante\u00bb, el primero que hacen en Catalu\u00f1a y con m\u00e1s motivo porque es para los Juegos del Mediterr\u00e1neo 2017. Una vez finalizados los Juegos, en un periodo de 3 o 4 meses el pabell\u00f3n se transformar\u00e1 en un complejo polideportivo, de 9.000 m2 de superficie y ser\u00e1 de primer nivel con instalaciones para todas las edades (piscinas climatizadas, salas para gimnasia, vestuarios, zona de restauraci\u00f3n, etc.)<\/p>\n<p>Para Joaquim Nin (Generalitat), el proyecto conllevar\u00e1 que los pr\u00f3ximos meses sean fren\u00e9ticos, pero \u00abtodo el mundo trabaja en la misma direcci\u00f3n\u00bb, afirm\u00f3. La Generalitat ha cedido los terrenos, cuya titularidad ha sido un problema durante a\u00f1os, a la URV por 75 a\u00f1os. La cooperaci\u00f3n en pol\u00edtica es necesaria y la Generalitat \u00abcumple con Tarragona\u00bb, manifest\u00f3.<\/p>\n<p>Para el alcalde Josep F\u00e9lix Ballesteros, el pabell\u00f3n es un equipamiento imprescindible para los Juegos del Mediterr\u00e1neo 2017. El proyecto dignificar\u00e1 un espacio ahora degradado y dar\u00e1 continuidad a la fachada urbana de la Avda. Llu\u00eds Companys, y por tanto har\u00e1 mejor el barrio. \u00abEs un ejemplo de la colaboraci\u00f3n p\u00fablico-privada, necesaria en estos tiempos para dar servicio a los ciudadanos\u00bb &#8211; -a\u00f1adi\u00f3-, y la URV ha sido el catalizador del proyecto \u00ab.<\/p>\n<p>El rector Josep Anton Ferr\u00e9 ha manifestado su satisfacci\u00f3n por poder proporcionar m\u00e1s servicios a los estudiantes, que los compartir\u00e1n con la ciudad, y ayudar a la realizaci\u00f3n de los Juegos, \u00abEs importante tambi\u00e9n poder ofrecer una buena infraestructura en el n\u00famero creciente de estudiantes internacionales que estudian en la URV \u00ab, explic\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La firma del contrato de construcci\u00f3n y explotaci\u00f3n del pabell\u00f3n y la residencia entre la empresa Viding Fitness y la URV, ha tenido lugar el martes 23 de junio a mediod\u00eda en el Rectorado. En el proyecto est\u00e1n implicados tambi\u00e9n la Generalitat, que ha cedido los terrenos a la Universidad por 75 a\u00f1os, el Ayuntamiento de Tarragona, impulsor de los Juegos del Mediterr\u00e1neo 2017, y la empresa RESA, operadora de la residencia universitaria existente y socia de Viding Fitness en este nuevo proyecto<\/p>\n","protected":false},"author":12,"featured_media":10057,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[113,94,124],"tags":[1806,1804,1805],"class_list":["post-10075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-campus-es","category-institucion","category-portada-es","tag-equipament-es","tag-pavello-esportiu-es","tag-residencia-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/10075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/comments?post=10075"}],"version-history":[{"count":0,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/posts\/10075\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media\/10057"}],"wp:attachment":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media?parent=10075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/categories?post=10075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/tags?post=10075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}