{"id":13909,"date":"2016-07-08T16:25:22","date_gmt":"2016-07-08T14:25:22","guid":{"rendered":"http:\/\/ddurv.taller.fesomia.net\/galeria-dimatges-2\/"},"modified":"2016-08-31T13:55:58","modified_gmt":"2016-08-31T11:55:58","slug":"galeria-dimatges","status":"publish","type":"page","link":"https:\/\/ddurv.taller.fesomia.net\/es\/galeria-dimatges\/","title":{"rendered":"Galer\u00eda de im\u00e1genes"},"content":{"rendered":"<h4><a href=\"http:\/\/ddurv.taller.fesomia.net\/galeria-1\/\">Personatges c\u00e8lebres<\/a><\/h4>\n<p>Recull d&#8217;imatges de les personalitats m\u00e9s rellevants que han passat per la nostra Universitat, a mode d&#8217;exemple trivial d&#8217;una galeria de fotos.<\/p>\n<hr \/>\n<h4><strong><a href=\"http:\/\/ddurv.taller.fesomia.net\/galeria-1\/\">Espais i edificis<\/a><\/strong><\/h4>\n<p>Recull d&#8217;imatges de les personalitats m\u00e9s rellevants que han passat per la nostra Universitat, a mode d&#8217;exemple trivial d&#8217;una galeria de fotos.<\/p>\n<hr \/>\n<h4><strong><a href=\"http:\/\/ddurv.taller.fesomia.net\/galeria-1\/\">Rectors i Directors<\/a><\/strong><\/h4>\n<p>Recull d&#8217;imatges de les personalitats m\u00e9s rellevants que han passat per la nostra Universitat, a mode d&#8217;exemple trivial d&#8217;una galeria de fotos.<\/p>\n<hr \/>\n<h4><strong><a href=\"http:\/\/ddurv.taller.fesomia.net\/galeria-1\/\">Premis i reconeixements<\/a><\/strong><\/h4>\n<p>Recull d&#8217;imatges de les personalitats m\u00e9s rellevants que han passat per la nostra Universitat, a mode d&#8217;exemple trivial d&#8217;una galeria de fotos.<\/p>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p>Personatges c\u00e8lebres<\/p>\n<p>Recull d&#8217;imatges de les personalitats m\u00e9s rellevants que han passat per la nostra Universitat, a mode d&#8217;exemple trivial d&#8217;una galeria de fotos.<\/p>\n<p>Espais i edificis<\/p>\n<p>Recull d&#8217;imatges de les personalitats m\u00e9s rellevants que han passat per la nostra Universitat, a mode d&#8217;exemple trivial d&#8217;una galeria de fotos.<\/p>\n<p>Rectors i Directors<\/p>\n<p>Recull d&#8217;imatges de les personalitats m\u00e9s rellevants que han passat per la nostra Universitat, a mode d&#8217;exemple trivial d&#8217;una galeria de fotos.<\/p>\n<p>Premis i reconeixements<\/p>\n<p>Recull d&#8217;imatges de les personalitats m\u00e9s rellevants que han passat<\/p>\n","protected":false},"author":15,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/galeries_parent.php","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"class_list":["post-13909","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/pages\/13909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/comments?post=13909"}],"version-history":[{"count":0,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/pages\/13909\/revisions"}],"wp:attachment":[{"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/media?parent=13909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ddurv.taller.fesomia.net\/es\/wp-json\/wp\/v2\/categories?post=13909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}